{"id":52150,"date":"2021-09-21T17:50:52","date_gmt":"2021-09-21T15:50:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/"},"modified":"2021-09-21T17:50:52","modified_gmt":"2021-09-21T15:50:52","slug":"cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/","title":{"rendered":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort"},"content":{"rendered":"<h5><strong>La Hamburger Hafen und Logistik AG (HHLA) y COSCO Shipping Ports Limited (CSPL) han concluido hoy con \u00e9xito las negociaciones sobre una participaci\u00f3n estrat\u00e9gica de CSPL en el HHLA Container Terminal Tollerort (CTT). CSPL, un operador de terminales que cotiza en Hong Kong y miembro del grupo COSCO Shipping, obtiene una participaci\u00f3n minoritaria del 35 por ciento en el terminal de contenedores de Hamburgo.<\/strong><\/h5>\n<p>(Hamburgo) HHLA ve en la participaci\u00f3n un fortalecimiento de la relaci\u00f3n con el socio chino, as\u00ed como una seguridad de planificaci\u00f3n sostenible para el terminal de contenedores Tollerort, con el fin de asegurar la ocupaci\u00f3n y el empleo en el puerto de Hamburgo. Con la participaci\u00f3n minoritaria de CSPL, el CTT se convertir\u00e1 en un llamado \u00abPreferred Hub\u00bb en Europa, es decir, un punto de transbordo preferido de COSCO, donde se concentran los flujos de carga.<\/p>\n<p>Angela Titzrath, presidenta del consejo de administraci\u00f3n de HHLA: \u00abEl mundo mar\u00edtimo est\u00e1 actualmente expuesto a cambios muy fuertes. Las relaciones comerciales de larga data y de confianza, como las que HHLA ha mantenido durante 40 a\u00f1os en el comercio de mercanc\u00edas con China, son por lo tanto especialmente importantes. Ya en 1982, se despach\u00f3 el primer buque de carga chino en Tollerort. Desde entonces, el terminal se ha convertido en un punto clave para los servicios de l\u00ednea de las actuales COSCO Shipping Lines. En este contexto, HHLA y COSCO persiguen igualmente el objetivo de asegurar un futuro exitoso para el CTT y una integraci\u00f3n a\u00fan m\u00e1s fuerte de los flujos log\u00edsticos chinos en el sitio de Hamburgo.\u00bb<\/p>\n<h5><strong>Terminal con perspectivas de desarrollo<\/strong><\/h5>\n<p>Zhang Dayu, director general de CSPL: \u00abEl terminal de contenedores Tollerort en Hamburgo es un pilar importante de la log\u00edstica en Europa y tiene muy buenas perspectivas de desarrollo para el futuro. Estamos deseando, junto con nuestro socio HHLA, aprovechar los potenciales existentes y desarrollar con \u00e9xito el sitio.\u00bb<\/p>\n<p>En el CTT, hoy en d\u00eda se despachan, entre otros, dos servicios de Extremo Oriente, un tr\u00e1fico del Mediterr\u00e1neo y un servicio de alimentaci\u00f3n del B\u00e1ltico de COSCO. A pesar de la participaci\u00f3n minoritaria acordada de CSPL, el CTT seguir\u00e1 estando abierto a todos los clientes navieros en la red de HHLA.<\/p>\n<p>El CTT es uno de los tres terminales de contenedores de HHLA en el puerto de Hamburgo. La instalaci\u00f3n cuenta con cuatro muelles y 14 gr\u00faas de contenedores. Aqu\u00ed se despachan, entre otros, los mayores buques portacontenedores de COSCO con una capacidad de 20,000 TEU o m\u00e1s. La estaci\u00f3n de tren propia del terminal est\u00e1 excelentemente conectada con el hinterland, con sus cinco v\u00edas, lo que permite mover mercanc\u00edas r\u00e1pidamente entre los mercados de destino europeos y el CTT.<\/p>\n<h5><strong>Casi un tercio de los contenedores de o hacia China<\/strong><\/h5>\n<p>El puerto de Hamburgo es el principal punto log\u00edstico para el tr\u00e1fico mar\u00edtimo y continental de mercanc\u00edas entre China y Europa. Casi un tercio de los contenedores que pasan por el borde del muelle en Hamburgo provienen de China o est\u00e1n destinados al mercado chino. A trav\u00e9s de la asociaci\u00f3n estrat\u00e9gica con CSPL, no solo se fortalece el CTT y la HHLA, sino tambi\u00e9n la posici\u00f3n de Hamburgo como hub log\u00edstico en el rango norte europeo y frente al \u00e1rea del B\u00e1ltico.<\/p>\n<p>La ejecuci\u00f3n de la transacci\u00f3n est\u00e1 sujeta a diversas aprobaciones de competencia y de derecho exterior. El consejo de supervisi\u00f3n de HHLA ya ha aprobado la participaci\u00f3n minoritaria.<\/p>\n<p>Foto: \u00a9 HHLA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Hamburger Hafen und Logistik AG (HHLA) y COSCO Shipping Ports Limited (CSPL) han concluido hoy con \u00e9xito las negociaciones sobre una participaci\u00f3n estrat\u00e9gica de CSPL<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-52150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Hamburger Hafen und Logistik AG (HHLA) y COSCO Shipping Ports Limited (CSPL) han concluido hoy con \u00e9xito las negociaciones sobre una participaci\u00f3n estrat\u00e9gica de CSPL [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T15:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1231\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort\",\"datePublished\":\"2021-09-21T15:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/\"},\"wordCount\":619,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HHLA_21.9.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/\",\"name\":\"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HHLA_21.9.21.jpg\",\"datePublished\":\"2021-09-21T15:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HHLA_21.9.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HHLA_21.9.21.jpg\",\"width\":1231,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/21\\\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/","og_locale":"es_ES","og_type":"article","og_title":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24","og_description":"La Hamburger Hafen und Logistik AG (HHLA) y COSCO Shipping Ports Limited (CSPL) han concluido hoy con \u00e9xito las negociaciones sobre una participaci\u00f3n estrat\u00e9gica de CSPL [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-21T15:50:52+00:00","og_image":[{"width":1231,"height":767,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/"},"author":{"name":"","@id":""},"headline":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort","datePublished":"2021-09-21T15:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/"},"wordCount":619,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/","url":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/","name":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg","datePublished":"2021-09-21T15:50:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HHLA_21.9.21.jpg","width":1231,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/21\/cosco-negocia-con-hhla-sobre-participacion-en-el-terminal-tollerort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"COSCO negocia con HHLA sobre participaci\u00f3n en el terminal Tollerort"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=52150"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/12314"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=52150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=52150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=52150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}