{"id":52012,"date":"2021-09-16T12:47:03","date_gmt":"2021-09-16T10:47:03","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/"},"modified":"2021-09-16T12:47:03","modified_gmt":"2021-09-16T10:47:03","slug":"karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/","title":{"rendered":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG"},"content":{"rendered":"<h5><strong>Hartmut Schick (59) se jubila a finales de 2021 tras 35 a\u00f1os en Daimler. Karl Deppen (55), actualmente director de Mercedes-Benz do Brasil, ser\u00e1 nombrado su sucesor en el consejo de Daimler Truck AG a partir del 1 de diciembre de 2021, responsable de Truck China, incluido el joint venture Beijing Foton Daimler Automotive con la marca Auman, y de las regiones de Jap\u00f3n e India con las marcas FUSO y BharatBenz.<\/strong><\/h5>\n<p>(Stuttgart) Tras 35 a\u00f1os en diversas funciones de liderazgo en el grupo Daimler, Hartmut Schick (59), miembro del consejo de Daimler Truck AG, responsable de Daimler Trucks Asia, se jubilar\u00e1 el 31 de diciembre de 2021. Su sucesor a partir del 1 de diciembre de 2021 ser\u00e1 Karl Deppen (55), actualmente responsable de la regi\u00f3n de Am\u00e9rica Latina de Mercedes-Benz Trucks and Buses.<\/p>\n<p>\u00abAgradezco a Hartmut Schick en nombre de todo el consejo y del consejo de supervisi\u00f3n por su extraordinario compromiso: durante m\u00e1s de tres d\u00e9cadas ha contribuido al exitoso desarrollo de nuestra empresa en diversas posiciones. En particular, como director de nuestra divisi\u00f3n de autobuses y luego como director de Daimler Trucks Asia, Hartmut Schick ha moldeado nuestro negocio de veh\u00edculos comerciales con su estilo de liderazgo inclusivo y motivador durante m\u00e1s de una d\u00e9cada y ha apostado por veh\u00edculos sin emisiones desde muy temprano\u00bb, dice Martin Daum, presidente del consejo de Daimler Truck AG y miembro del consejo de Daimler AG. \u00abAl mismo tiempo, me complace haber conseguido para su sucesi\u00f3n a Karl Deppen, un gerente internacionalmente muy experimentado con una s\u00f3lida experiencia en el sector de veh\u00edculos comerciales y un destacado conocimiento de Asia.<\/p>\n<h5><strong>Experiencia en diferentes continentes<\/strong><\/h5>\n<p>Karl Deppen conoce el negocio global de veh\u00edculos comerciales a trav\u00e9s de diversas asignaciones en diferentes ubicaciones. En Europa, Am\u00e9rica del Norte y del Sur, as\u00ed como en Asia, ha llevado a cabo con \u00e9xito muchos proyectos. Con esta valiosa combinaci\u00f3n de experiencia y know-how, Karl Deppen es la persona adecuada para nuestro negocio de veh\u00edculos comerciales en Asia. Junto con mi equipo de gesti\u00f3n, doy una c\u00e1lida bienvenida a Karl Deppen en el consejo de Daimler Truck AG.\u00bb<\/p>\n<p>Daum contin\u00faa: \u00abYa estamos muy bien posicionados en Asia y listos para llevar el negocio al siguiente nivel: nuestro objetivo es aumentar la rentabilidad y nuestra contribuci\u00f3n potencial a las ganancias de Daimler Truck. Vemos a Asia como la regi\u00f3n con las mayores perspectivas de crecimiento a medio plazo. Especialmente en China, donde con nuestro cami\u00f3n pesado de la marca Mercedes-Benz &#8216;hecho en China para China&#8217; abriremos un nuevo cap\u00edtulo y adem\u00e1s comercializaremos con \u00e9xito la marca Auman a trav\u00e9s de nuestro joint venture Beijing Foton Daimler Automotive y nuestro socio Beiqi Foton Motor.\u00bb<\/p>\n<h5><strong>Sobre Hartmut Schick<\/strong><\/h5>\n<p>Hartmut Schick se uni\u00f3 en 1986 al \u00e1rea de investigaci\u00f3n central de Daimler-Benz AG tras completar sus estudios de ingenier\u00eda mec\u00e1nica. Despu\u00e9s de pasar a la producci\u00f3n de autom\u00f3viles, trabaj\u00f3 a partir de 1990 en el \u00e1rea de marketing de DASA en M\u00fanich. En 1993 asumi\u00f3 la direcci\u00f3n de la secretar\u00eda principal y la direcci\u00f3n de la oficina del presidente del consejo. Como jefe de la oficina de planificaci\u00f3n del presidente del consejo de Daimler-Benz AG, Hartmut Schick regres\u00f3 a Stuttgart en 1995. En 1997 fue encargado de establecer la planta de Mercedes-Benz en Juiz de Fora (Brasil) como jefe de producci\u00f3n y log\u00edstica. En 1999 dirigi\u00f3 el equipo del CEO de DaimlerChrysler. Desde 2002 fue responsable de la comunicaci\u00f3n global del grupo Daimler y en 2009 asumi\u00f3 la direcci\u00f3n del \u00e1rea de negocio de Daimler Buses y la presidencia de la gesti\u00f3n de EvoBus GmbH. Desde abril de 2018, Hartmut Schick es responsable del negocio de Daimler Truck en Asia.<\/p>\n<h5><strong>Sobre Karl Deppen<\/strong><\/h5>\n<p>Karl Deppen se uni\u00f3 al grupo en 1990 y trabaj\u00f3 hasta 2007 en diversas posiciones de liderazgo en compras y log\u00edstica, principalmente con un enfoque en veh\u00edculos comerciales. Sus etapas profesionales lo llevaron a estancias de varios a\u00f1os en EE. UU., Turqu\u00eda y Jap\u00f3n. All\u00ed, Karl Deppen fue responsable de compras y log\u00edstica de transporte en Mitsubishi Fuso. En 2007 asumi\u00f3 la direcci\u00f3n del proyecto estrat\u00e9gico para el cami\u00f3n Mercedes-Benz Atego. De 2011 a 2014, Karl Deppen fue responsable del desarrollo de l\u00edderes a nivel mundial en Daimler, antes de trasladarse a Daimler Greater China Ltd. en Pek\u00edn como CFO. Posteriormente, fue responsable del control de costos de Mercedes-Benz AG. Desde mayo de 2020, Karl Deppen es CEO de Mercedes-Benz do Brazil Ltda. y responsable de la regi\u00f3n de Am\u00e9rica Latina de Mercedes-Benz Trucks and Buses.<\/p>\n<p>La sucesi\u00f3n de Karl Deppen en Brasil se anunciar\u00e1 lo antes posible.<\/p>\n<p>Foto: \u00a9 Daimler Truck<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hartmut Schick (59) se jubila a finales de 2021 tras 35 a\u00f1os en Daimler. Karl Deppen (55), actualmente director de Mercedes-Benz do Brasil, ser\u00e1 nombrado su<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-52012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Hartmut Schick (59) se jubila a finales de 2021 tras 35 a\u00f1os en Daimler. Karl Deppen (55), actualmente director de Mercedes-Benz do Brasil, ser\u00e1 nombrado su [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T10:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1449\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG\",\"datePublished\":\"2021-09-16T10:47:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/\"},\"wordCount\":807,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_Truck_16.9.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/\",\"name\":\"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_Truck_16.9.21.jpg\",\"datePublished\":\"2021-09-16T10:47:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_Truck_16.9.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_Truck_16.9.21.jpg\",\"width\":1449,\"height\":812},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/16\\\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/","og_locale":"es_ES","og_type":"article","og_title":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24","og_description":"Hartmut Schick (59) se jubila a finales de 2021 tras 35 a\u00f1os en Daimler. Karl Deppen (55), actualmente director de Mercedes-Benz do Brasil, ser\u00e1 nombrado su [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-16T10:47:03+00:00","og_image":[{"width":1449,"height":812,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/"},"author":{"name":"","@id":""},"headline":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG","datePublished":"2021-09-16T10:47:03+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/"},"wordCount":807,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/","url":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/","name":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg","datePublished":"2021-09-16T10:47:03+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_Truck_16.9.21.jpg","width":1449,"height":812},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/16\/karl-deppen-sucede-a-hartmut-schick-en-daimler-truck-ag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Karl Deppen sucede a Hartmut Schick en Daimler Truck AG"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=52012"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/52012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/12362"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=52012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=52012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=52012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}