{"id":51982,"date":"2021-09-15T19:27:45","date_gmt":"2021-09-15T17:27:45","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/"},"modified":"2021-09-15T19:27:45","modified_gmt":"2021-09-15T17:27:45","slug":"swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/","title":{"rendered":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza"},"content":{"rendered":"<h5><strong>La Swissterminal AG, uno de los principales proveedores suizos de productos log\u00edsticos integrados, se ha propuesto el objetivo de reducir las emisiones de CO2 de todas sus operaciones a cero. Un paso importante en el camino hacia este objetivo ya se ha logrado: la empresa opera sus ubicaciones de terminal en Suiza al 100% con electricidad de fuentes de energ\u00eda renovables.<\/strong><\/h5>\n<p>(Frenkendorf) Para lograr un suministro energ\u00e9tico completamente sostenible, Swissterminal ha firmado un contrato con Renergy GmbH, un corredor de electricidad independiente suizo. Este contrato prev\u00e9 el suministro de energ\u00eda a las ubicaciones de terminal en Suiza, inicialmente hasta 2024, que proviene al 100% de la energ\u00eda hidroel\u00e9ctrica suiza.<\/p>\n<p>\u00abCon la adquisici\u00f3n de energ\u00eda ecol\u00f3gica, subrayamos la amplia estrategia de sostenibilidad de nuestra empresa. Adem\u00e1s, nos estamos preparando para el aumento de los precios de la energ\u00eda y los costos relacionados con las emisiones de CO2\u00bb, explica el CEO de Swissterminal, Roman Mayer. \u00abEste es un paso importante para alcanzar nuestros objetivos: reducir nuestras emisiones de CO2, ayudar a nuestros clientes a reducir su propia huella ecol\u00f3gica y contribuir a hacer que la industria log\u00edstica sea m\u00e1s sostenible.\u00bb<\/p>\n<p>La energ\u00eda hidroel\u00e9ctrica tiene un factor de CO2 de 0 kg\/GJ. Por lo tanto, Swissterminal puede evitar emisiones indirectas de gases de efecto invernadero derivadas de la compra de electricidad gracias al contrato de energ\u00eda ecol\u00f3gica.<\/p>\n<h5><strong>Estrategia de sostenibilidad impulsada continuamente<\/strong><\/h5>\n<p>En los \u00faltimos a\u00f1os, Swissterminal ha impulsado continuamente su estrategia de sostenibilidad y ha desarrollado soluciones para reducir las emisiones. Al mismo tiempo, se ha centrado en la expansi\u00f3n de las actividades comerciales. As\u00ed, el proveedor de servicios log\u00edsticos integrados ofrece, por ejemplo, opciones de transporte sostenibles como conexiones ferroviarias de bajas emisiones, como una conexi\u00f3n entre Suiza y China desde abril de 2020. A finales de noviembre de 2020, Swissterminal tambi\u00e9n introdujo un servicio de transporte fluvial, la forma m\u00e1s ecol\u00f3gica de transporte interior, entre las ubicaciones de terminal en Suiza y los principales puertos mar\u00edtimos de Europa, Rotterdam y Amberes.<\/p>\n<p>\u00abLa industria log\u00edstica ha contribuido en gran medida a las emisiones de gases de efecto invernadero en el pasado. Por eso, para nosotros en Swissterminal es muy importante demostrar nuestro compromiso con un futuro m\u00e1s ecol\u00f3gico\u00bb, explica Mayer. \u00abA\u00fan queda mucho por hacer, pero esperamos que el anuncio de hoy inspire a otras empresas a tomar m\u00e1s medidas y demuestre que las energ\u00edas renovables son viables en la log\u00edstica.\u00bb<\/p>\n<p>Foto: \u00a9 Swissterminal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Swissterminal AG, uno de los principales proveedores suizos de productos log\u00edsticos integrados, se ha propuesto el objetivo de reducir las emisiones de CO2 de todas<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12374,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-51982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Swissterminal AG, uno de los principales proveedores suizos de productos log\u00edsticos integrados, se ha propuesto el objetivo de reducir las emisiones de CO2 de todas [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T17:27:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1194\" \/>\n\t<meta property=\"og:image:height\" content=\"791\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza\",\"datePublished\":\"2021-09-15T17:27:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swissterminal_15.9.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/\",\"name\":\"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swissterminal_15.9.21.jpg\",\"datePublished\":\"2021-09-15T17:27:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swissterminal_15.9.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Swissterminal_15.9.21.jpg\",\"width\":1194,\"height\":791},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/09\\\/15\\\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/","og_locale":"es_ES","og_type":"article","og_title":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24","og_description":"La Swissterminal AG, uno de los principales proveedores suizos de productos log\u00edsticos integrados, se ha propuesto el objetivo de reducir las emisiones de CO2 de todas [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-09-15T17:27:45+00:00","og_image":[{"width":1194,"height":791,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/"},"author":{"name":"","@id":""},"headline":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza","datePublished":"2021-09-15T17:27:45+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/","url":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/","name":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg","datePublished":"2021-09-15T17:27:45+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Swissterminal_15.9.21.jpg","width":1194,"height":791},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/09\/15\/swissterminal-utiliza-energia-ecologica-en-sus-ubicaciones-en-suiza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Swissterminal utiliza energ\u00eda ecol\u00f3gica en sus ubicaciones en Suiza"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=51982"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/12374"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=51982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=51982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=51982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}