{"id":51533,"date":"2021-08-31T18:44:27","date_gmt":"2021-08-31T16:44:27","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/"},"modified":"2021-08-31T18:44:27","modified_gmt":"2021-08-31T16:44:27","slug":"dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/","title":{"rendered":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \u00abGerman Ports\u00bb"},"content":{"rendered":"<p>Una soluci\u00f3n alemana conjunta para el proceso de liberaci\u00f3n digitalizado de contenedores de importaci\u00f3n est\u00e1 siendo desarrollada por los proveedores de servicios especializados en sistemas de comunidad portuaria DAKOSY AG, Hamburgo, y dbh Logistics IT AG, Bremen. Este a\u00f1o, se espera que las primeras navieras y transportistas se conecten a la plataforma, que ser\u00e1 comercializada bajo la etiqueta \u00abGerman Ports\u00bb.<\/p>\n<p>(Hamburgo\/Bremen) DAKOSY y dbh han creado las condiciones para estandarizar y digitalizar el proceso de liberaci\u00f3n de contenedores de importaci\u00f3n en los puertos mar\u00edtimos alemanes de Hamburgo, Bremerhaven, Bremen y Wilhelmshaven. Tanto desde el punto de vista del proceso como desde el tecnol\u00f3gico, los participantes tienen varias opciones para utilizar la aplicaci\u00f3n para el proceso de liberaci\u00f3n.<\/p>\n<p>DAKOSY y dbh ofrecen a los usuarios por primera vez la tecnolog\u00eda blockchain. La idoneidad y viabilidad pr\u00e1ctica de la blockchain para el proceso de liberaci\u00f3n ya ha sido confirmada en el marco del proyecto de investigaci\u00f3n IHATEC ROboB. Otro desencadenante para la r\u00e1pida implementaci\u00f3n de este proyecto es el alto inter\u00e9s actual de los transportistas en digitalizar el proceso de liberaci\u00f3n.<\/p>\n<p>El acceso al nuevo proceso es igualmente sencillo para transportistas, empresas de transporte, transportadores y terminales. El apoderado de DAKOSY, Dirk Gladiator, informa: \u00abNuestra soluci\u00f3n para el proceso de liberaci\u00f3n digitalizado se basa en plataformas y procesos existentes que ya son ampliamente utilizados por los participantes en los puertos mar\u00edtimos alemanes.\u00bb La aplicaci\u00f3n estar\u00e1 disponible tanto en el sistema de comunidad portuaria de Hamburgo como en el de Bremen. En Hamburgo, esto se llevar\u00e1 a cabo en el marco de la Import Message Platform (IMP), en los puertos de Bremen y Wilhelmshaven dentro de la Business Integration Platform (BIP).<\/p>\n<h5><strong>Construcci\u00f3n de una blockchain<\/strong><\/h5>\n<p>\u00abParalelamente a las plataformas consolidadas IMP y BIP, estamos estableciendo el marco para la blockchain, para ofrecerla en el siguiente paso como una alternativa h\u00edbrida. La fase de prueba est\u00e1 en preparaci\u00f3n\u00bb, describe Holger H\u00fcbner, jefe del \u00e1rea de soluciones portuarias de dbh, el concepto y asegura: \u00abla liberaci\u00f3n digitalizada cumple con todos los requisitos de seguridad y verificabilidad de las identidades.\u00bb<\/p>\n<p>Hasta ahora, la liberaci\u00f3n generalmente no se comunica de forma digital, sino que se distribuye por medios cl\u00e1sicos a trav\u00e9s de fax, correo electr\u00f3nico o tel\u00e9fono entre los participantes. \u00abEl proceso manual genera un alto esfuerzo para todos los involucrados, ya que los actores deben dialogar bilateralmente sobre cada contenedor individual para organizar permisos y devoluciones de contenedores vac\u00edos\u00bb, explican H\u00fcbner y Gladiator de manera coincidente.<\/p>\n<p>Con el uso de las plataformas ya establecidas IMP y BIP, as\u00ed como la opci\u00f3n de ampliaci\u00f3n con la blockchain, ahora se han resuelto las altas exigencias en cuanto a permisos de acceso y procesos de TI seguros. La liberaci\u00f3n es un proceso sensible, ya que la referencia de liberaci\u00f3n autoriza al titular a recibir el contenedor con a menudo considerables valores de mercanc\u00edas.<\/p>\n<h5><strong>Informaci\u00f3n de fondo sobre el proceso de liberaci\u00f3n<\/strong><\/h5>\n<p>Fundamentalmente, una liberaci\u00f3n o referencia de liberaci\u00f3n intercambiada entre las partes involucradas autoriza la recogida de la mercanc\u00eda en el terminal de contenedores. El proceso se inicia con la solicitud de liberaci\u00f3n del transportista al armador. El armador libera un contenedor tan pronto como se han pagado las facturas correspondientes por el transporte y env\u00eda al transportista, como su cliente, la llamada referencia de liberaci\u00f3n, que autoriza la recogida de la mercanc\u00eda. El transportista encarga a su proveedor de servicios (por ejemplo, una empresa de transporte o un operador ferroviario) la recogida de un contenedor del terminal. Para ello, transfiere el derecho de recogida en forma de referencia de liberaci\u00f3n al proveedor de servicios. El proveedor de servicios debe identificarse en el terminal con la referencia para recibir el contenedor y llevarlo a su destino. El terminal recibe la referencia de liberaci\u00f3n directamente del armador y verifica si coincide con la referencia presentada por el conductor al recoger la mercanc\u00eda.<\/p>\n<p>Foto: \u00a9 HHLA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una soluci\u00f3n alemana conjunta para el proceso de liberaci\u00f3n digitalizado de contenedores de importaci\u00f3n est\u00e1 siendo desarrollada por los proveedores de servicios especializados en sistemas de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561,1559],"tags":[],"class_list":["post-51533","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para &quot;German Ports&quot; - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para &quot;German Ports&quot; - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Una soluci\u00f3n alemana conjunta para el proceso de liberaci\u00f3n digitalizado de contenedores de importaci\u00f3n est\u00e1 siendo desarrollada por los proveedores de servicios especializados en sistemas de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T16:44:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \u00abGerman Ports\u00bb\",\"datePublished\":\"2021-08-31T16:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/\"},\"wordCount\":708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/\",\"name\":\"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \\\"German Ports\\\" - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-08-31T16:44:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \u00abGerman Ports\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \"German Ports\" - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/","og_locale":"es_ES","og_type":"article","og_title":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \"German Ports\" - Loginfo24","og_description":"Una soluci\u00f3n alemana conjunta para el proceso de liberaci\u00f3n digitalizado de contenedores de importaci\u00f3n est\u00e1 siendo desarrollada por los proveedores de servicios especializados en sistemas de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-31T16:44:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/"},"author":{"name":"","@id":""},"headline":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \u00abGerman Ports\u00bb","datePublished":"2021-08-31T16:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/"},"wordCount":708,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/","url":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/","name":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \"German Ports\" - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-08-31T16:44:27+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/dakosy-y-dbh-digitalizan-el-proceso-de-liberacion-para-german-ports\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"DAKOSY y dbh digitalizan el proceso de liberaci\u00f3n para \u00abGerman Ports\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=51533"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51533\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=51533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=51533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=51533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}