{"id":51521,"date":"2021-08-31T18:22:28","date_gmt":"2021-08-31T16:22:28","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/"},"modified":"2021-08-31T18:22:28","modified_gmt":"2021-08-31T16:22:28","slug":"berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/","title":{"rendered":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen"},"content":{"rendered":"<p>El especialista del sector en equipamiento industrial y tecnolog\u00eda de estanter\u00edas, la Berger Group, se traslada dentro de Korntal-M\u00fcnchingen a una ubicaci\u00f3n m\u00e1s del doble de grande. La nueva instalaci\u00f3n es f\u00e1cilmente accesible desde la autopista A81 y la carretera federal B10. Proveedores, socios comerciales, clientes y empleados se benefician de esta inversi\u00f3n orientada al futuro.<\/p>\n<p><span style=\"font-family: 'Cambria',serif\">(Korntal-M\u00fcnchingen) La superficie de oficina, dise\u00f1ada seg\u00fan el concepto de espacio abierto, aumenta a 500 m\u00b2, mientras que la superficie de almacenamiento crece incluso a 5.500 m\u00b2. De este modo, Berger no solo responde al desarrollo actual del negocio, sino que tambi\u00e9n consolida su stock de mercanc\u00edas, suministros y piezas de repuesto en un solo lugar. Esto genera ahorros de energ\u00eda para electricidad y calefacci\u00f3n, as\u00ed como para el transporte interno. Un efecto ambiental adicional proviene de la iluminaci\u00f3n LED utilizada en todo el edificio.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Ahora hay 50 plazas de aparcamiento disponibles para visitantes y empleados. Las entregas, recogidas y cargas de camiones propias se pueden gestionar simult\u00e1neamente en 4 rampas y 5 puertas a nivel del suelo. Adem\u00e1s, Berger ha invertido en un nuevo sistema de estanter\u00edas de palets Artus con refuerzo s\u00edsmico para el equipamiento del almac\u00e9n, que garantiza una estabilidad significativamente mayor.<\/span><\/p>\n<h4><strong><span style=\"font-family: 'Cambria',serif\">Reducir los tiempos de entrega y aumentar el servicio al cliente<\/span><\/strong><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">Para una organizaci\u00f3n del trabajo lo m\u00e1s eficiente posible, se han digitalizado todos los procesos entre la recepci\u00f3n de pedidos y la entrega. Esto es posible gracias a una nueva infraestructura de TI y sistemas de software para el procesamiento de pedidos, la preparaci\u00f3n de pedidos sin documentos y un nuevo sistema de gesti\u00f3n de almacenes. En toda la log\u00edstica, los empleados son apoyados por terminales de datos m\u00f3viles. Con este paso, tambi\u00e9n se reducen posibles fuentes de error y los tiempos de entrega.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Los puestos de trabajo en la oficina y en las estaciones de montaje en el almac\u00e9n se han dise\u00f1ado seg\u00fan principios ergon\u00f3micos. Para un descanso relajante, hay salas sociales y diversas \u00e1reas de descanso disponibles. Otro factor para retener a los empleados, que en su mayor\u00eda son de larga trayectoria y con experiencia, es la permanencia de la empresa en la zona de influencia tradicional de Stuttgart.<\/span><\/p>\n<h4><b><span style=\"font-family: 'Cambria',serif\">La mayor inversi\u00f3n en la historia de la empresa<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">Con la mayor inversi\u00f3n en la historia de la empresa, la Berger Group establece la base para implementar de manera coherente y exitosa su estrategia de crecimiento en los pr\u00f3ximos a\u00f1os. La Berger Group ha sido durante m\u00e1s de 60 a\u00f1os uno de los principales proveedores de soluciones personalizadas para almacenamiento, equipamiento industrial y de oficina. Junto con sus clientes, la empresa desarrolla, planifica y realiza soluciones t\u00e9cnicamente y econ\u00f3micamente \u00f3ptimas.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Las diferentes \u00e1reas de negocio, Berger Estanter\u00edas, Berger Taquillas y Berger Dynamics, representan competencia t\u00e9cnica y de asesoramiento. Ya sea soluciones completas elaboradas en la construcci\u00f3n de estanter\u00edas, equipamiento moderno de \u00e1reas sociales o sistemas de desplazamiento altamente eficientes, la empresa ofrece calidad y experiencia de primer nivel y se encarga de la gesti\u00f3n de proyectos desde la primera idea hasta la puesta en marcha. M\u00e1s de 5.000 soluciones personalizadas y adaptadas a las necesidades ya han sido desarrolladas, planificadas y realizadas. Desde la sede de la empresa en M\u00fcnchingen, la empresa apuesta por productos fabricados en Europa y garantiza cercan\u00eda al cliente y un excelente servicio. Con BERGER Ventures, se desarrollan nuevos modelos de negocio innovadores y digitales.<\/span><\/p>\n<h4><b><span style=\"font-family: 'Cambria',serif\">M\u00e1s de 50.000 art\u00edculos para necesidades comerciales<\/span><\/b><\/h4>\n<p><span style=\"font-family: 'Cambria',serif\">La amplia gama de equipamiento para almacenamiento, industrial y de oficina incluye m\u00e1s de 50.000 art\u00edculos para necesidades comerciales y est\u00e1 disponible en un cat\u00e1logo especializado y en la tienda en l\u00ednea.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Berger apoya a sus clientes con una amplia gama de productos y en todas las cuestiones relacionadas con el pedido electr\u00f3nico, proporcionando todos los datos de productos y pedidos relevantes en diversos formatos y apoyando en la implementaci\u00f3n de TI. Las ventas y el n\u00famero de empleados han crecido continuamente durante a\u00f1os. Entre los clientes satisfechos se encuentran peque\u00f1as, medianas y grandes empresas como Porsche, Flaconi, H\u00e4fele, Kaufland, Bosch, KiK, ebm-papst, BLG y muchas otras empresas reconocidas en Alemania, Europa y en el extranjero.<\/span><\/p>\n<p><span style=\"font-family: 'Cambria',serif\">Foto: \u00a9 Berger<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El especialista del sector en equipamiento industrial y tecnolog\u00eda de estanter\u00edas, la Berger Group, se traslada dentro de Korntal-M\u00fcnchingen a una ubicaci\u00f3n m\u00e1s del doble de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-51521","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El especialista del sector en equipamiento industrial y tecnolog\u00eda de estanter\u00edas, la Berger Group, se traslada dentro de Korntal-M\u00fcnchingen a una ubicaci\u00f3n m\u00e1s del doble de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T16:22:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen\",\"datePublished\":\"2021-08-31T16:22:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/\"},\"wordCount\":752,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/\",\"name\":\"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-08-31T16:22:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/31\\\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/","og_locale":"es_ES","og_type":"article","og_title":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24","og_description":"El especialista del sector en equipamiento industrial y tecnolog\u00eda de estanter\u00edas, la Berger Group, se traslada dentro de Korntal-M\u00fcnchingen a una ubicaci\u00f3n m\u00e1s del doble de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-31T16:22:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/"},"author":{"name":"","@id":""},"headline":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen","datePublished":"2021-08-31T16:22:28+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/"},"wordCount":752,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/","url":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/","name":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-08-31T16:22:28+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/31\/berger-group-se-traslada-a-una-nueva-construccion-en-korntal-munchingen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Berger Group se traslada a una nueva construcci\u00f3n en Korntal-M\u00fcnchingen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=51521"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51521\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=51521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=51521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=51521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}