{"id":51454,"date":"2021-08-28T19:09:06","date_gmt":"2021-08-28T17:09:06","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/"},"modified":"2021-08-28T19:09:06","modified_gmt":"2021-08-28T17:09:06","slug":"el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/","title":{"rendered":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo"},"content":{"rendered":"<p>Para reconocer las oportunidades del transporte fluvial ecol\u00f3gico y aprovechar su potencial, Hafen Hamburg Marketing (HHM), junto con la Alianza Elbe-Seitenkanal (BESK) y la Alianza Elbe (EA), ha encargado un estudio para determinar el car\u00e1cter del sistema de la red de v\u00edas navegables interiores del norte y noreste de Alemania.<\/p>\n<p>(Hamburgo) El transporte fluvial tambi\u00e9n desempe\u00f1a un papel importante en los tr\u00e1ficos de hinterland del puerto de Hamburgo. Durante una conferencia de prensa en l\u00ednea transmitida en vivo, se discutieron ayer los resultados de los an\u00e1lisis de mercado y se formularon recomendaciones de acci\u00f3n.<\/p>\n<p>\u201cLa importancia de los puertos interiores y del transporte fluvial apenas se percibe o se percibe muy poco y debe destacarse m\u00e1s claramente\u201d, apela Gunnar Platz, de Planco. \u201cEs necesario dejar claro que, para la econom\u00eda regional, en la mayor\u00eda de los casos no hay alternativa a los tr\u00e1ficos de transporte fluvial. La falta de transporte fluvial conducir\u00eda a escasez de suministros y p\u00e9rdidas de empleo en la regi\u00f3n\u201d, enfatiza Platz. Por ejemplo, se ha determinado que 4.600 puestos de trabajo dependen directa e indirectamente del puerto de L\u00fcneburg. En 2020, se manejaron alrededor de 340.000 toneladas en L\u00fcneburg, lo que equivale a 13 empleados por cada 1.000 toneladas de carga. Adem\u00e1s, las 14,4 millones de toneladas de mercanc\u00edas que actualmente se transportan por v\u00eda fluvial en el tr\u00e1fico de hinterland del puerto mar\u00edtimo no podr\u00edan ser absorbidas por otros modos de transporte. Estas cifras subrayan la importancia de las v\u00edas navegables y destacan, sobre todo, que las inversiones en el mantenimiento y la expansi\u00f3n de las v\u00edas fluviales son indispensables para la regi\u00f3n.<\/p>\n<h5><strong>Numerosas medidas de reparaci\u00f3n<\/strong><\/h5>\n<p>Para garantizar el transporte por v\u00eda fluvial en la regi\u00f3n, en los pr\u00f3ximos a\u00f1os se deben llevar a cabo numerosas medidas de reparaci\u00f3n en la infraestructura. Cuellos de botella, como la esclusa de Scharnebeck o las secciones faltantes del Elba, ya est\u00e1n siendo renovados o se est\u00e1n eliminando con la implementaci\u00f3n del concepto general del Elba (GKE) para aumentar la capacidad y, por lo tanto, la rentabilidad y competitividad del transporte fluvial en el futuro. \u201cEl estudio muestra de manera impresionante qu\u00e9 potencial tiene el transporte fluvial en el norte de Alemania. Sin embargo, debemos invertir masivamente en la infraestructura y renovar o construir nuestras estructuras para aprovechar estos potenciales de manera sostenible\u201d, confirma Tobias Siewert, de BESK. \u201cCon la nueva esclusa de L\u00fcneburg, podemos iniciar un cambio notable hacia la v\u00eda fluvial. Pero tambi\u00e9n est\u00e1 claro que las fases de planificaci\u00f3n y construcci\u00f3n deben acelerarse.\u201d<\/p>\n<h5><strong>Potenciales de desv\u00edo en el sector de mercanc\u00edas a granel<\/strong><\/h5>\n<p>Estos potenciales de desv\u00edo son especialmente visibles en el sector de mercanc\u00edas a granel. En la regi\u00f3n de Magdeburgo\/Braunschweig, por ejemplo, se importan alrededor de 6 millones de toneladas de mineral de hierro y 2,1 millones de toneladas de carb\u00f3n a trav\u00e9s de Hamburgo por ferrocarril. Tambi\u00e9n en el tr\u00e1fico de contenedores, Stefan Kunze, de HHM, ve un gran potencial: en la regi\u00f3n de Braunschweig\/Wolfsburg, se transportan alrededor de 55.000 TEU por cami\u00f3n al a\u00f1o, y en la regi\u00f3n de Magdeburgo, otros 50.000 TEU. \u201cPartes de estas cantidades podr\u00edan ser f\u00e1cilmente absorbidas por el transporte fluvial\u201d, explica. Adem\u00e1s, el GKE garantizar\u00e1 en el futuro la posibilidad de tr\u00e1ficos de contenedores de tres capas hasta Riesa, la conexi\u00f3n de puertos como Wittenberge y la recuperaci\u00f3n de cuotas de mercado en los tr\u00e1ficos por encima de Magdeburgo. Estos potenciales de desv\u00edo son especialmente relevantes en relaci\u00f3n con los objetivos clim\u00e1ticos de la Uni\u00f3n Europea y Alemania.<\/p>\n<p>El transporte fluvial es, con mucho, el modo de transporte m\u00e1s ecol\u00f3gico. Por lo tanto, se puede destacar, por ejemplo, la reducci\u00f3n de los contaminantes del aire como un incentivo a la inversi\u00f3n, explica Platz. \u201cLa digitalizaci\u00f3n en el transporte fluvial tambi\u00e9n debe ser impulsada de manera consistente\u201d, dice Platz. De esta manera, tambi\u00e9n se podr\u00eda implementar una mejor planificaci\u00f3n de rutas y determinar un tiempo de llegada (ETA) m\u00e1s preciso. Adem\u00e1s, las cadenas de informaci\u00f3n entre los puertos mar\u00edtimos e interiores podr\u00edan optimizarse. Esto, a su vez, fortalecer\u00eda la competitividad del transporte fluvial en la regi\u00f3n frente a otros modos de transporte.<\/p>\n<h5><strong>Hacer visibles los potenciales<\/strong><\/h5>\n<p>Los puertos interiores en la regi\u00f3n aseguran empleo y creaci\u00f3n de valor, el transporte por v\u00eda fluvial es ecol\u00f3gico y econ\u00f3mico. Esto ha demostrado el estudio conjunto. Ahora se trata de enfrentar los desaf\u00edos identificados y aprovechar los potenciales. \u201cPara ello, es necesario hacerlos visibles, crear incentivos para inversiones y mejorar las condiciones marco\u201d, resume Sebastian Poser, de EA. \u201cDebemos hacer que el transporte fluvial sea m\u00e1s consciente tanto en el mercado como en la pol\u00edtica.\u201d Los socios del proyecto est\u00e1n decididos a promover el transporte fluvial en la regi\u00f3n con la ayuda de estos hallazgos y prepararlo para el futuro. \u201cDe un mayor transporte fluvial se benefician tanto los puertos como la econom\u00eda cargadora en la regi\u00f3n\u201d, resume Tobias Siewert.<\/p>\n<p>El estudio completo se puede descargar desde nuestra p\u00e1gina web a partir del 6 de septiembre de 2021. M\u00e1s detalles sobre el transporte fluvial, as\u00ed como la grabaci\u00f3n del evento y las presentaciones:<br \/><a href=\"https:\/\/www.hafen-hamburg.de\/de\/special\/barging-ahead-das-transportmittel-der-zukunft-heisst-binnenschiff\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.hafen-hamburg.de\/de\/special\/barging-ahead-das-transportmittel-der-zukunft-heisst-binnenschiff\/<\/a><\/p>\n<p>Foto: \u00a9 Hafen Hamburg<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para reconocer las oportunidades del transporte fluvial ecol\u00f3gico y aprovechar su potencial, Hafen Hamburg Marketing (HHM), junto con la Alianza Elbe-Seitenkanal (BESK) y la Alianza Elbe<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-51454","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Para reconocer las oportunidades del transporte fluvial ecol\u00f3gico y aprovechar su potencial, Hafen Hamburg Marketing (HHM), junto con la Alianza Elbe-Seitenkanal (BESK) y la Alianza Elbe [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-28T17:09:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo\",\"datePublished\":\"2021-08-28T17:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/\"},\"wordCount\":956,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/\",\"name\":\"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-08-28T17:09:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/28\\\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/","og_locale":"es_ES","og_type":"article","og_title":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24","og_description":"Para reconocer las oportunidades del transporte fluvial ecol\u00f3gico y aprovechar su potencial, Hafen Hamburg Marketing (HHM), junto con la Alianza Elbe-Seitenkanal (BESK) y la Alianza Elbe [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-28T17:09:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/"},"author":{"name":"","@id":""},"headline":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo","datePublished":"2021-08-28T17:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/"},"wordCount":956,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/","url":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/","name":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-08-28T17:09:06+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/28\/el-transporte-fluvial-es-importante-para-el-trafico-de-hinterland-en-el-puerto-de-hamburgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"El transporte fluvial es importante para el tr\u00e1fico de hinterland en el puerto de Hamburgo"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=51454"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/51454\/revisions"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=51454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=51454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=51454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}