{"id":28338,"date":"2021-08-08T17:41:04","date_gmt":"2021-08-08T15:41:04","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/"},"modified":"2025-12-15T13:14:39","modified_gmt":"2025-12-15T12:14:39","slug":"los-cuatro-finalistas-del-logix-award-2021-estan-definidos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/","title":{"rendered":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos"},"content":{"rendered":"<p>Los cuatro finalistas para el Logix Award 2021 est\u00e1n definidos. Un jurado independiente, presidido por el Prof. Dr. Christian Kille, se reuni\u00f3 el 28 de julio de 2021 en W\u00fcrzburg y tuvo que decidir entre un denso campo de solicitantes de alto nivel. La entrega del Logix Award tendr\u00e1 lugar el 11 de octubre de 2021 durante la Expo Real en M\u00fanich.<\/p>\n<p>(Weiterstadt) El Logix Award 2021, el premio a proyectos destacados de inmuebles log\u00edsticos en Alemania, que se otorga cada dos a\u00f1os, entra en su fase final. El 28 de julio, el jurado independiente se reuni\u00f3 en la Universidad de W\u00fcrzburg bajo la presidencia del Prof. Dr. Christian Kille, de la Universidad de Ciencias Aplicadas W\u00fcrzburg-Schweinfurt, FHWS. El jurado evalu\u00f3 y discuti\u00f3 un total de nueve proyectos, que previamente hab\u00edan sido nominados de aproximadamente 20 solicitudes presentadas.<\/p>\n<p>Por primera vez se utiliz\u00f3 un procedimiento de evaluaci\u00f3n interactivo, que mediante un mapa de calor captura la idoneidad de los proyectos en funci\u00f3n de los criterios de solicitud pertinentes. Se premiar\u00e1n los inmuebles log\u00edsticos que satisfacen en gran medida las demandas de los usuarios e inversores, as\u00ed como aquellos que destacan en aspectos ecol\u00f3gicos, sociales, econ\u00f3micos y urban\u00edsticos.<\/p>\n<p>Para determinar los cuatro finalistas, de los cuales finalmente se conocer\u00e1 al ganador del Logix Award 2021, los miembros del jurado formaron inicialmente dos grupos y luego superpusieron sus resultados. As\u00ed, finalmente quedaron cuatro proyectos en la carrera. El Prof. Kille coment\u00f3: \u00abEl campo de solicitantes fue extremadamente denso este a\u00f1o, lo que llev\u00f3 a intensas discusiones del jurado sobre los finalistas y el inmueble ganador.\u00bb Es notable que el tema de la sostenibilidad ecol\u00f3gica ha llegado a todos los solicitantes del Logix Award: \u00abLos cuatro finalistas pudieron mostrar una clara singularidad en otros aspectos del proceso hasta la finalizaci\u00f3n en comparaci\u00f3n con sus competidores\u00bb, dijo Kille.<\/p>\n<h5><strong>Los cuatro inmuebles log\u00edsticos seleccionados<\/strong><\/h5>\n<ul>\n<li><strong>Baytree Deutschland GmbH<\/strong>, centro de distribuci\u00f3n para Samsung SDS Europe, Magdeburg: El proyecto, con aproximadamente 64,000 m\u00b2 de superficie log\u00edstica, se destaca especialmente por numerosas medidas para el bienestar de los empleados, con terrazas al aire libre, huertos y estanques, etc., un dise\u00f1o exterior atractivo, un alto est\u00e1ndar ecol\u00f3gico, as\u00ed como una alta capacidad de reutilizaci\u00f3n y buena conexi\u00f3n de transporte.<\/li>\n<li><strong>Dietz AG,<\/strong> centro de distribuci\u00f3n para Puma, Geiselwind: Para el jurado, la selecci\u00f3n del objeto, con aproximadamente 64,000 m\u00b2 de superficie log\u00edstica, se bas\u00f3 especialmente en el exitoso proceso de asentamiento que involucr\u00f3 a todas las partes y la cooperaci\u00f3n con el municipio, el paquete integral de sostenibilidad (certificaci\u00f3n LEED Oro), la importancia estrat\u00e9gica con la concentraci\u00f3n de log\u00edstica B2B (Retail) y B2C (E-Commerce) en un solo lugar, as\u00ed como la amplia consideraci\u00f3n de aspectos sociales.<\/li>\n<li><strong>GARBE Industrial Real Estate GmbH<\/strong>, centro log\u00edstico para Amazon, Achim: Aqu\u00ed, el jurado destac\u00f3 especialmente la multi-piso del centro log\u00edstico utilizando tecnolog\u00eda rob\u00f3tica innovadora como respuesta a la continua escasez de espacio, el alto n\u00famero de empleos que se est\u00e1n creando (actualmente ya 1,900 empleos), la inclusi\u00f3n de la poblaci\u00f3n y los representantes de intereses en un di\u00e1logo directo, las amplias medidas de sostenibilidad (certificaci\u00f3n DGNB Platino), la mejora del espacio p\u00fablico, as\u00ed como amplias medidas sociales.<\/li>\n<li><strong>Prologis Germany Management GmbH<\/strong>, centro de distribuci\u00f3n para el comerciante en l\u00ednea Euziel International, Datteln: Este objeto es, sobre todo, el primer inmueble log\u00edstico con est\u00e1ndar WELL Platino (monitoreo de la calidad del aire y medici\u00f3n del clima, reducci\u00f3n de niveles de ruido, \u00e1reas verdes interiores, dispensadores de agua potable y numerosas cocinas, zona de convivencia, \u00e1reas exteriores atractivas). El jurado tambi\u00e9n consider\u00f3 especialmente digna de premio la compleja rehabilitaci\u00f3n de la antigua zona industrial de aproximadamente 50,000 m\u00b2 en la regi\u00f3n del Ruhr, marcada por la transformaci\u00f3n estructural. Adem\u00e1s, el inmueble est\u00e1 certificado seg\u00fan DGNB Platino y se destaca por una muy buena conexi\u00f3n de transporte que permite un uso trimodal.<\/li>\n<\/ul>\n<h5><strong>Hace dos a\u00f1os excepcional - hoy est\u00e1ndar<\/strong><\/h5>\n<p>El Dr. Malte-Maria M\u00fcnchow, portavoz de la Iniciativa Logix y director de compra y venta de inmuebles especiales, Deka Immobilien Investment GmbH, coment\u00f3 el resultado de la siguiente manera: \u00abNo es sorprendente que se necesitaran discusiones significativas para que el jurado identificara a los finalistas realmente destacados. Lo que hace dos a\u00f1os era excepcional, hoy ya se clasifica como est\u00e1ndar. Por lo tanto, este a\u00f1o los proyectos que est\u00e1n al frente son aquellos que van un paso m\u00e1s all\u00e1 en varios aspectos, son a\u00fan m\u00e1s innovadores y se destacan del campo en general muy bueno.\u00bb<\/p>\n<p>Qu\u00e9 proyecto recibir\u00e1 al final el codiciado premio permanecer\u00e1 en secreto hasta el 11 de octubre de 2021. Solo en la ceremonia de entrega en el marco de la feria de bienes inmuebles comerciales Expo Real en M\u00fanich se anunciar\u00e1 al ganador del Logix Award 2021 entre los finalistas. Seg\u00fan la informaci\u00f3n actual, la Expo Real se llevar\u00e1 a cabo como un evento presencial.<\/p>\n<h5><strong>Un jurado selecto decide<\/strong><\/h5>\n<p>Adem\u00e1s del Prof. Christian Kille, el jurado est\u00e1 compuesto por los siguientes miembros: Dr. Claus-Peter Amberger, miembro de la junta del proveedor de servicios log\u00edsticos LOXXESS AG; Alexander Handschuh, Asociaci\u00f3n Alemana de Ciudades y Comunas; Doreen Kruschina, planificaci\u00f3n y gesti\u00f3n de la construcci\u00f3n; Wolfgang K\u00fchling, oficina de arquitectura K\u00fchling; Robert Mergens, DP DHL Corporate Real Estate Management; Matthias Pieringer, Huss Verlag, as\u00ed como Uwe Veres-Homm, Instituto Fraunhofer Grupo de Trabajo SCS.<\/p>\n<p>Foto: \u00a9 Logix<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cuatro finalistas para el Logix Award 2021 est\u00e1n definidos. Un jurado independiente, presidido por el Prof. Dr. Christian Kille, se reuni\u00f3 el 28 de julio<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-28338","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Los cuatro finalistas para el Logix Award 2021 est\u00e1n definidos. Un jurado independiente, presidido por el Prof. Dr. Christian Kille, se reuni\u00f3 el 28 de julio [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-08T15:41:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:14:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos\",\"datePublished\":\"2021-08-08T15:41:04+00:00\",\"dateModified\":\"2025-12-15T12:14:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/\"},\"wordCount\":954,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/\",\"name\":\"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-08-08T15:41:04+00:00\",\"dateModified\":\"2025-12-15T12:14:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/08\\\/08\\\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/","og_locale":"es_ES","og_type":"article","og_title":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24","og_description":"Los cuatro finalistas para el Logix Award 2021 est\u00e1n definidos. Un jurado independiente, presidido por el Prof. Dr. Christian Kille, se reuni\u00f3 el 28 de julio [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-08-08T15:41:04+00:00","article_modified_time":"2025-12-15T12:14:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/"},"author":{"name":"","@id":""},"headline":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos","datePublished":"2021-08-08T15:41:04+00:00","dateModified":"2025-12-15T12:14:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/"},"wordCount":954,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/","url":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/","name":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-08-08T15:41:04+00:00","dateModified":"2025-12-15T12:14:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/08\/08\/los-cuatro-finalistas-del-logix-award-2021-estan-definidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los cuatro finalistas del Logix Award 2021 est\u00e1n definidos"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=28338"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28338\/revisions"}],"predecessor-version":[{"id":50927,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28338\/revisions\/50927"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=28338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=28338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=28338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}