{"id":28013,"date":"2021-07-26T16:53:36","date_gmt":"2021-07-26T14:53:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/"},"modified":"2025-12-15T13:12:50","modified_gmt":"2025-12-15T12:12:50","slug":"dachser-abastece-la-capital-berlin-con-vacunas","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/","title":{"rendered":"DACHSER abastece la capital Berl\u00edn con vacunas"},"content":{"rendered":"<p>En Berl\u00edn, el Senado conf\u00eda en la sucursal de DACHSER en Berl\u00edn-Sch\u00f6nefeld para la log\u00edstica de vacunas, bas\u00e1ndose en una asociaci\u00f3n probada y bien establecida. Desde el inicio de la pandemia, DACHSER ha podido ayudar con el almacenamiento y la distribuci\u00f3n de mascarillas y equipos de protecci\u00f3n, adem\u00e1s de realizar negocios interesantes.<\/p>\n<p>(Berl\u00edn-Sch\u00f6nefeld) \u00abTodo esto es realmente incre\u00edble. Pero como equipo lo hemos logrado.\u00bb Cuando Olaf Schmidt repasa el a\u00f1o pasado y los \u00faltimos meses en su mente, todav\u00eda se sorprende y sonr\u00ede satisfecho. La historia que cuenta el gerente general del centro log\u00edstico de DACHSER en Berl\u00edn Brandeburgo en Sch\u00f6nefeld trata sobre la pandemia de COVID-19, una carrera contra el tiempo y una log\u00edstica inteligente para garantizar el suministro confiable de equipos de protecci\u00f3n y vacunas a la poblaci\u00f3n.<\/p>\n<p>Pero vayamos por partes. A mediados de mayo del a\u00f1o pasado, la administraci\u00f3n del Senado de Berl\u00edn se acerc\u00f3 al centro log\u00edstico de DACHSER en Berl\u00edn Brandeburgo para organizar r\u00e1pidamente el almacenamiento y la distribuci\u00f3n de mascarillas y equipos de protecci\u00f3n. \u00abHab\u00eda una gran presi\u00f3n para actuar\u00bb, recuerda Schmidt. La decisi\u00f3n de optar por DACHSER se tom\u00f3 muy r\u00e1pidamente. A finales de junio, el centro log\u00edstico pudo comprometerse a almacenar 130 contenedores mar\u00edtimos. En julio, adem\u00e1s, tres Boeing 747 estaban en camino. \u00abEn solo cuatro semanas, de repente ten\u00edamos 8,000 palets nuevos en stock.\u00bb<\/p>\n<p>\u00abPero eso fue solo el comienzo\u00bb, dice Falk Wenk, gerente de log\u00edstica de contratos en el centro log\u00edstico de Berl\u00edn Brandeburgo. \u00abEl stock de palets almacenados aument\u00f3 a 11,000 hasta enero de 2021. Eso exigi\u00f3 todos nuestros recursos y sistemas.\u00bb El almacenamiento y la distribuci\u00f3n de equipos de protecci\u00f3n, mascarillas y pruebas r\u00e1pidas, dice Wenk, es log\u00edstica de contratos cl\u00e1sica. \u00abLos procesos en DACHSER est\u00e1n bien establecidos incluso en alta carga. Luego llegaron las vacunas.\u00bb<\/p>\n<h5><strong>Un llamado de auxilio de la administraci\u00f3n del Senado<\/strong><\/h5>\n<p>El 27 de diciembre, la Agencia Europea de Medicamentos (EMA) otorg\u00f3 las primeras autorizaciones de vacunas. En anticipaci\u00f3n a esta decisi\u00f3n previsible, la administraci\u00f3n del Senado de Berl\u00edn ya hab\u00eda contactado a DACHSER el 7 de diciembre: \u00abTenemos un problema&#8230;\u00bb, as\u00ed comenz\u00f3 la conversaci\u00f3n, recuerda el gerente general Schmidt. \u00abUstedes tienen un sistema log\u00edstico que ya nos ayud\u00f3 con el equipo de protecci\u00f3n. \u00bfPueden gestionar tambi\u00e9n un almac\u00e9n de vacunas?\u00bb<\/p>\n<p>\u00abLa log\u00edstica de vacunas fue un desaf\u00edo para todos con muchas incertidumbres; no hab\u00eda un modelo a seguir\u00bb, dice Schmidt. \u00abComenz\u00f3 con un proveedor farmac\u00e9utico que ten\u00eda que almacenar las vacunas en un almac\u00e9n asegurado por el ej\u00e9rcito. All\u00ed hay congeladores ultrabajos para temperaturas de menos 75 grados. Luego organizamos los procesos del almac\u00e9n con el sistema de gesti\u00f3n de almacenes Mikado de DACHSER y pusimos en marcha la entrega. Nuestras tareas tambi\u00e9n inclu\u00edan la adquisici\u00f3n de contenedores de refrigeraci\u00f3n adecuados para el transporte y la entrega a los seis centros de vacunaci\u00f3n de Berl\u00edn, a las farmacias de los hospitales y a los equipos de vacunaci\u00f3n m\u00f3viles.\u00bb Al mismo tiempo, la entrega de equipos de protecci\u00f3n y, sobre todo, de pruebas r\u00e1pidas para las escuelas continu\u00f3.<\/p>\n<p>\u00abNos alegra poder contribuir a la sociedad y a la lucha contra la pandemia con nuestro conocimiento log\u00edstico.\u00bb<\/p>\n<h5><strong>Recurrir a sistemas de TI<\/strong><\/h5>\n<p>El esfuerzo organizativo fue considerable, a\u00f1ade Olaf Schmidt. Esto inclu\u00eda, entre otras cosas, conferencias diarias con todos los participantes del proyecto de vacunaci\u00f3n de Berl\u00edn, la colaboraci\u00f3n con el proveedor farmac\u00e9utico y la coordinaci\u00f3n de la escolta policial de los veh\u00edculos.<\/p>\n<p>Para llevar la vacuna de manera segura y controlada farmac\u00e9uticamente a los centros de vacunaci\u00f3n y garantizar la trazabilidad de los lotes individuales, DACHSER pudo acceder a sus sistemas de producci\u00f3n log\u00edstica Domino para el transporte terrestre y Mikado para el almacenamiento. \u00abEsa fue la condici\u00f3n b\u00e1sica para un proceso de log\u00edstica de vacunas ordenado y proactivo\u00bb, enfatiza Schmidt. \u00abAl entregar la primera dosis, tambi\u00e9n planificamos la segunda dosis necesaria en el proceso de vacunaci\u00f3n y reservamos las capacidades correspondientes con anticipaci\u00f3n.\u00bb<\/p>\n<h5><strong>Soluciones ingeniosas del taller<\/strong><\/h5>\n<p>Para la log\u00edstica de vacunas, la sucursal de DACHSER en Berl\u00edn tuvo que adquirir r\u00e1pidamente alrededor de 150 cajas de transporte farmac\u00e9utico refrigeradas. Esto fue posible gracias a una relaci\u00f3n comercial de larga data. Dado que los acumuladores de fr\u00edo de estas cajas requieren 48 horas para su reacondicionamiento, DACHSER coloc\u00f3 r\u00e1pidamente un puente de cambio t\u00e9rmico en el almac\u00e9n. \u00abNuestros empleados del taller fabricaron estanter\u00edas a medida para el voluminoso enfriamiento de los acumuladores. Tambi\u00e9n los separadores que construyeron para los acumuladores de fr\u00edo fueron soluciones ingeniosas para perfeccionar tanto el manejo como el reacondicionamiento. Fue emocionante ver c\u00f3mo todos en nuestro equipo se involucraron\u00bb, dice Schmidt.<\/p>\n<p>Que la log\u00edstica de vacunas en tiempos de pandemia es una tarea emocionante en muchos aspectos no solo se reflej\u00f3 en almacenes y transportes vigilados. Debido a que en marzo una entrega se detuvo debido a una furgoneta de entrega defectuosa del fabricante de vacunas, el tabloide titul\u00f3 \u00ab\u00a1Caos de vacunas!\u00bb \u00abSin embargo, nosotros y nuestra parte de la cadena de suministro no tuvimos nada que ver con eso\u00bb, dice Schmidt. Hoy se r\u00ede de la breve agitaci\u00f3n medi\u00e1tica. \u00abLa atenci\u00f3n hacia DACHSER ha crecido sin duda en Berl\u00edn y va mucho m\u00e1s all\u00e1 del proyecto\u00bb, dice Schmidt. Y con orgullo a\u00f1ade: \u00abNos alegra poder contribuir a la sociedad y a la lucha contra la pandemia con nuestro conocimiento log\u00edstico.\u00bb<\/p>\n<p>Foto: \u00a9 Dachser<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Berl\u00edn, el Senado conf\u00eda en la sucursal de DACHSER en Berl\u00edn-Sch\u00f6nefeld para la log\u00edstica de vacunas, bas\u00e1ndose en una asociaci\u00f3n probada y bien establecida. Desde<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-28013","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"En Berl\u00edn, el Senado conf\u00eda en la sucursal de DACHSER en Berl\u00edn-Sch\u00f6nefeld para la log\u00edstica de vacunas, bas\u00e1ndose en una asociaci\u00f3n probada y bien establecida. Desde [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-26T14:53:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:12:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DACHSER abastece la capital Berl\u00edn con vacunas\",\"datePublished\":\"2021-07-26T14:53:36+00:00\",\"dateModified\":\"2025-12-15T12:12:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/\"},\"wordCount\":1001,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/\",\"name\":\"DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-07-26T14:53:36+00:00\",\"dateModified\":\"2025-12-15T12:12:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/26\\\/dachser-abastece-la-capital-berlin-con-vacunas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DACHSER abastece la capital Berl\u00edn con vacunas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/","og_locale":"es_ES","og_type":"article","og_title":"DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24","og_description":"En Berl\u00edn, el Senado conf\u00eda en la sucursal de DACHSER en Berl\u00edn-Sch\u00f6nefeld para la log\u00edstica de vacunas, bas\u00e1ndose en una asociaci\u00f3n probada y bien establecida. Desde [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-26T14:53:36+00:00","article_modified_time":"2025-12-15T12:12:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/"},"author":{"name":"","@id":""},"headline":"DACHSER abastece la capital Berl\u00edn con vacunas","datePublished":"2021-07-26T14:53:36+00:00","dateModified":"2025-12-15T12:12:50+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/"},"wordCount":1001,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/","url":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/","name":"DACHSER abastece la capital Berl\u00edn con vacunas - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-07-26T14:53:36+00:00","dateModified":"2025-12-15T12:12:50+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/26\/dachser-abastece-la-capital-berlin-con-vacunas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"DACHSER abastece la capital Berl\u00edn con vacunas"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=28013"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28013\/revisions"}],"predecessor-version":[{"id":50283,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/28013\/revisions\/50283"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=28013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=28013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=28013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}