{"id":27972,"date":"2021-07-23T20:15:07","date_gmt":"2021-07-23T18:15:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/"},"modified":"2025-12-15T13:12:38","modified_gmt":"2025-12-15T12:12:38","slug":"los-camiones-electricos-reciben-un-80-de-subvencion-estatal","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/","title":{"rendered":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal"},"content":{"rendered":"<p>Volvo Trucks actualmente ofrece cinco modelos de camiones el\u00e9ctricos. El Ministerio Federal de Transporte (BMVI) anuncia la implementaci\u00f3n de la directriz de subvenci\u00f3n para veh\u00edculos comerciales con propulsiones alternativas tras la aprobaci\u00f3n de la Comisi\u00f3n Europea. Entre las medidas se incluye una prima de compra para camiones con propulsi\u00f3n el\u00e9ctrica. Esta prev\u00e9 una subvenci\u00f3n de hasta el 80 por ciento de los costos adicionales en comparaci\u00f3n con un cami\u00f3n di\u00e9sel.<\/p>\n<p>(Ismaning) Volvo actualmente ofrece cinco modelos de camiones el\u00e9ctricos. Se ha decidido una prima de compra para camiones con propulsi\u00f3n el\u00e9ctrica de hasta el 80 % de los costos adicionales en comparaci\u00f3n con un cami\u00f3n di\u00e9sel.<\/p>\n<p>Volvo Trucks da la bienvenida a la subvenci\u00f3n para la compra de veh\u00edculos comerciales con propulsiones alternativas y al apoyo en la expansi\u00f3n de la infraestructura de carga. Esto allana el camino para una r\u00e1pida escalaci\u00f3n de las cifras de matriculaci\u00f3n de camiones el\u00e9ctricos en Alemania y Europa. Desde 2019, los camiones el\u00e9ctricos de Volvo pueden adquirirse con un peso de hasta 27 toneladas. Los modelos Volvo FL Electric y Volvo FE Electric se producen en serie desde 2020 y ya se han entregado en Alemania. La gama de camiones el\u00e9ctricos se ampliar\u00e1 con tres modelos el\u00e9ctricos m\u00e1s hasta 2022. La producci\u00f3n en serie de los modelos Volvo FH Electric, Volvo FM Electric y Volvo FMX Electric est\u00e1 prevista para la segunda mitad de 2022. Volvo Trucks tiene como objetivo vender solo camiones con propulsiones alternativas para 2040. En 2030, Volvo Trucks espera generar la mitad de sus ingresos con veh\u00edculos comerciales el\u00e9ctricos.<\/p>\n<h5><strong>Implementar medidas clave concretas<\/strong><\/h5>\n<p>El Ministerio Federal de Transporte (BMVI) quiere implementar las directrices del programa de protecci\u00f3n clim\u00e1tica ahora con tres medidas clave concretas:<\/p>\n<ol>\n<li>Los costos adicionales al comprar un cami\u00f3n el\u00e9ctrico en comparaci\u00f3n con un cami\u00f3n di\u00e9sel ser\u00e1n subvencionados hasta en un 80 por ciento.<\/li>\n<li>Subvenci\u00f3n del 80 por ciento de los gastos totales del proyecto elegibles para la operaci\u00f3n de los veh\u00edculos comerciales respetuosos con el clima, incluyendo la infraestructura de carga y repostaje necesaria.<\/li>\n<li>Subvenci\u00f3n del 50 por ciento de los gastos del proyecto elegibles para la elaboraci\u00f3n de estudios de viabilidad sobre las posibilidades de uso de veh\u00edculos comerciales respetuosos con el clima, as\u00ed como para la construcci\u00f3n o expansi\u00f3n de la infraestructura correspondiente.<\/li>\n<\/ol>\n<h5><strong>1.600 millones de euros hasta 2024<\/strong><\/h5>\n<p>Con estas medidas, se busca que los veh\u00edculos comerciales respetuosos con el clima sean competitivos y aumentar la seguridad de planificaci\u00f3n e inversi\u00f3n para las empresas.<\/p>\n<p>Hasta el a\u00f1o 2024, el BMVI destinar\u00e1 aproximadamente 1.600 millones de euros para la subvenci\u00f3n de la adquisici\u00f3n de veh\u00edculos comerciales respetuosos con el clima, as\u00ed como aproximadamente 5.000 millones de euros para la construcci\u00f3n de la infraestructura de carga y repostaje (turismos y camiones).<\/p>\n<p>Los detalles m\u00e1s espec\u00edficos de la subvenci\u00f3n se regular\u00e1n en el texto de la directriz y en la primera convocatoria de subvenciones, que se publicar\u00e1n en breve.<\/p>\n<p>Foto: \u00a9 Volvo Trucks<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volvo Trucks actualmente ofrece cinco modelos de camiones el\u00e9ctricos. El Ministerio Federal de Transporte (BMVI) anuncia la implementaci\u00f3n de la directriz de subvenci\u00f3n para veh\u00edculos comerciales<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-27972","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Volvo Trucks actualmente ofrece cinco modelos de camiones el\u00e9ctricos. El Ministerio Federal de Transporte (BMVI) anuncia la implementaci\u00f3n de la directriz de subvenci\u00f3n para veh\u00edculos comerciales [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-23T18:15:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:12:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal\",\"datePublished\":\"2021-07-23T18:15:07+00:00\",\"dateModified\":\"2025-12-15T12:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/\"},\"wordCount\":538,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/\",\"name\":\"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-07-23T18:15:07+00:00\",\"dateModified\":\"2025-12-15T12:12:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/07\\\/23\\\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/","og_locale":"es_ES","og_type":"article","og_title":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24","og_description":"Volvo Trucks actualmente ofrece cinco modelos de camiones el\u00e9ctricos. El Ministerio Federal de Transporte (BMVI) anuncia la implementaci\u00f3n de la directriz de subvenci\u00f3n para veh\u00edculos comerciales [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-07-23T18:15:07+00:00","article_modified_time":"2025-12-15T12:12:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/"},"author":{"name":"","@id":""},"headline":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal","datePublished":"2021-07-23T18:15:07+00:00","dateModified":"2025-12-15T12:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/"},"wordCount":538,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/","url":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/","name":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-07-23T18:15:07+00:00","dateModified":"2025-12-15T12:12:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/07\/23\/los-camiones-electricos-reciben-un-80-de-subvencion-estatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los camiones el\u00e9ctricos reciben un 80% de subvenci\u00f3n estatal"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=27972"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27972\/revisions"}],"predecessor-version":[{"id":50203,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27972\/revisions\/50203"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=27972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=27972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=27972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}