{"id":27333,"date":"2021-06-29T17:37:18","date_gmt":"2021-06-29T15:37:18","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/"},"modified":"2025-12-15T13:09:24","modified_gmt":"2025-12-15T12:09:24","slug":"agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/","title":{"rendered":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos"},"content":{"rendered":"<p>J\u00fcrgen Steinmetz, director general de la IHK Mittlerer Niederrhein, recientemente entreg\u00f3 el manual &#8216;Microdep\u00f3sitos en la cooperaci\u00f3n intermunicipal - Del concepto a la implementaci\u00f3n&#8217; al Ministro de Transporte de NRW, Hendrik W\u00fcst. El estudio fue realizado por agiplan GmbH y el Instituto Fraunhofer para el flujo de materiales y log\u00edstica IML.<\/p>\n<p>(M\u00fclheim Ruhr) El volumen de tr\u00e1fico en las ciudades est\u00e1 aumentando, y desde la pandemia de COVID-19, el tr\u00e1fico de entrega a trav\u00e9s de pedidos en l\u00ednea ha crecido a\u00fan m\u00e1s. Los atascos, la falta de aparcamiento y la contaminaci\u00f3n ambiental en los centros urbanos son las consecuencias. Una posible soluci\u00f3n a estos problemas es la creaci\u00f3n de microdep\u00f3sitos: las ubicaciones sirven como base log\u00edstica para mensajeros, servicios expr\u00e9s y empresas de paqueter\u00eda. Desde all\u00ed, se recorre la llamada \u00faltima milla, en este caso el camino desde el microdep\u00f3sito hasta el destinatario, utilizando bicicletas de carga ecol\u00f3gicas y veh\u00edculos el\u00e9ctricos peque\u00f1os. De este modo, se reduce el tr\u00e1fico en los centros urbanos, as\u00ed como las emisiones de CO<sub>2<\/sub>.<\/p>\n<p>Para investigar c\u00f3mo se pueden establecer y operar con \u00e9xito microdep\u00f3sitos en las ciudades de M\u00f6nchengladbach, Krefeld y Neuss, la C\u00e1mara de Comercio e Industria (IHK) Mittlerer Niederrhein encarg\u00f3 un estudio en dos partes. Agiplan llev\u00f3 a cabo el estudio junto con el Fraunhofer IML y public\u00f3 un manual con los resultados. Este fue entregado el 24 de junio de 2021 por J\u00fcrgen Steinmetz, director general de la IHK Mittlerer Niederrhein, al Ministro de Transporte de NRW, Hendrik W\u00fcst.<\/p>\n<h5><strong>Ubicaciones potencialmente adecuadas presentadas<\/strong><\/h5>\n<p>El manual se basa en el estudio de viabilidad para el desarrollo de microdep\u00f3sitos publicado en 2019. Para la segunda parte, los cient\u00edficos intercambiaron ideas con municipios, propietarios de inmuebles y servicios de paqueter\u00eda. En el manual se presentan ubicaciones potencialmente adecuadas en las distintas ciudades y se analizan econ\u00f3micamente.<\/p>\n<p>\u00abNuestro estudio muestra a las ciudades medianas c\u00f3mo pueden gestionar eficazmente el tr\u00e1fico de mercanc\u00edas en la \u00faltima milla mediante el uso inteligente de microdep\u00f3sitos, aliviando el tr\u00e1fico y protegiendo el clima. El modelo de operaci\u00f3n cooperativa que recomendamos involucra a todos los actores municipales y privados involucrados. Adem\u00e1s de las empresas locales, los ciudadanos se benefician, ya que pueden disfrutar de una menor emisi\u00f3n de CO2 y un menor volumen de tr\u00e1fico\u00bb, explica el Dr. Christian Jacobi, socio gerente de agiplan GmbH.<\/p>\n<p>\u00abLos conocimientos que el proyecto sobre la operaci\u00f3n de microdep\u00f3sitos en el Niederrhein permite son de gran importancia para futuros conceptos de dise\u00f1o eficiente de la \u00faltima milla en la log\u00edstica en general\u00bb, dice el Prof. Uwe Clausen, director del Instituto Fraunhofer IML.<\/p>\n<p>El estudio fue financiado por el Ministerio de Transporte de NRW.<\/p>\n<p>Foto: \u00a9 agiplan<\/p>\n<h4><strong>Estudio disponible para descarga aqu\u00ed (haga clic en la imagen):<\/strong><\/h4>\n<p><a href=\"https:\/\/www.agiplan.de\/wp-content\/uploads\/2021\/06\/IHK_MNR_Leitfaden_Microdepots_48S_3b_2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12406 \" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg\" alt=\"\" width=\"198\" height=\"281\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00fcrgen Steinmetz, director general de la IHK Mittlerer Niederrhein, recientemente entreg\u00f3 el manual &#8216;Microdep\u00f3sitos en la cooperaci\u00f3n intermunicipal - Del concepto a la implementaci\u00f3n&#8217; al Ministro<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-27333","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"J\u00fcrgen Steinmetz, director general de la IHK Mittlerer Niederrhein, recientemente entreg\u00f3 el manual &#8216;Microdep\u00f3sitos en la cooperaci\u00f3n intermunicipal - Del concepto a la implementaci\u00f3n&#8217; al Ministro [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T15:37:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos\",\"datePublished\":\"2021-06-29T15:37:18+00:00\",\"dateModified\":\"2025-12-15T12:09:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/agiplan_29.6.21_2.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/\",\"name\":\"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/agiplan_29.6.21_2.jpg\",\"datePublished\":\"2021-06-29T15:37:18+00:00\",\"dateModified\":\"2025-12-15T12:09:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/agiplan_29.6.21_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/agiplan_29.6.21_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/29\\\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/","og_locale":"es_ES","og_type":"article","og_title":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24","og_description":"J\u00fcrgen Steinmetz, director general de la IHK Mittlerer Niederrhein, recientemente entreg\u00f3 el manual &#8216;Microdep\u00f3sitos en la cooperaci\u00f3n intermunicipal - Del concepto a la implementaci\u00f3n&#8217; al Ministro [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-29T15:37:18+00:00","article_modified_time":"2025-12-15T12:09:24+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/"},"author":{"name":"","@id":""},"headline":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos","datePublished":"2021-06-29T15:37:18+00:00","dateModified":"2025-12-15T12:09:24+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/","url":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/","name":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg","datePublished":"2021-06-29T15:37:18+00:00","dateModified":"2025-12-15T12:09:24+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/agiplan_29.6.21_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/29\/agiplan-presenta-estudio-sobre-la-implementacion-de-microdepositos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"agiplan presenta estudio sobre la implementaci\u00f3n de microdep\u00f3sitos"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=27333"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27333\/revisions"}],"predecessor-version":[{"id":48932,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/27333\/revisions\/48932"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=27333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=27333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=27333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}