{"id":26590,"date":"2022-01-18T14:00:01","date_gmt":"2022-01-18T13:00:01","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/"},"modified":"2022-01-18T14:00:01","modified_gmt":"2022-01-18T13:00:01","slug":"arvato-supply-chain-instala-nueva-planta-solar-en-gennep","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/","title":{"rendered":"Arvato Supply Chain instala nueva planta solar en Gennep"},"content":{"rendered":"<h5><strong>Arvato Supply Chain Solutions invierte masivamente en tecnolog\u00edas ecol\u00f3gicas como parte de su estrategia de sostenibilidad. Hasta ahora, el proveedor internacional de servicios de cadena de suministro y comercio electr\u00f3nico ha gastado alrededor de 800.000 euros para hacer que los centros de log\u00edstica y distribuci\u00f3n en su red mundial sean m\u00e1s sostenibles mediante diversas medidas.<\/strong><\/h5>\n<section class=\"section\">\n<div class=\"container mx-auto\">\n<article class=\"text-image\">\n<div class=\"text-image__content\">\n<div class=\"text-image__richtext press__intro\">\n<p>(G\u00fctersloh\/Gennep) Esto incluye, entre otras cosas, la instalaci\u00f3n de potentes sistemas de fotovoltaica, que actualmente est\u00e1n planificados o ya implementados en siete ubicaciones. Recientemente, se puso en funcionamiento una planta solar con 27.076 paneles solares en el sitio operativo de Heijen, en el municipio neerland\u00e9s de Gennep. Con esto, es uno de los proyectos m\u00e1s grandes de techos en los Pa\u00edses Bajos. Tiene una capacidad de m\u00e1s de 10.000 megavatios-hora (MWh) al a\u00f1o y cubre el consumo energ\u00e9tico de aproximadamente 3.300 hogares.<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/section>\n<section class=\"section\">\n<div class=\"container mx-auto\">\n<article class=\"text-image\">\n<div class=\"text-image__content\">\n<div class=\"text-image__richtext\">\n<p>Lo especial de esta planta solar es que la energ\u00eda generada no solo puede ser utilizada por Arvato Supply Chain Solutions en Gennep. Tambi\u00e9n suministra electricidad verde a otras ubicaciones de Arvato Supply Chain Solutions en los Pa\u00edses Bajos.<\/p>\n<p>\u00abCon la planta fotovoltaica en Gennep, Arvato Supply Chain Solutions reduce su huella de CO<sub>2<\/sub> en 4.100 toneladas al a\u00f1o, lo que equivale a la compensaci\u00f3n anual de m\u00e1s de 416.600 \u00e1rboles. Por lo tanto, la planta contribuye significativamente al balance ambiental de la empresa\u00bb, explica Marcel Orth, quien ha impulsado el proyecto como Gerente de Excelencia Operativa en Arvato Supply Chain Solutions en los Pa\u00edses Bajos. El objetivo de todo el grupo Bertelsmann, al que tambi\u00e9n pertenece Arvato Supply Chain Solutions, es ser completamente neutro en carbono para el a\u00f1o 2030. \u00abEsto incluye, entre otras cosas, que en el marco de nuestra propia estrategia clim\u00e1tica, cambiemos el consumo de electricidad al 100% a energ\u00eda verde y reduzcamos los gases de efecto invernadero relacionados con el sitio (Alcance 1+2) en un 50%\u00bb, explica Andreas Barth, Presidente de Tecnolog\u00eda y Jefe del Grupo de Responsabilidad Corporativa y Sostenibilidad en Arvato Supply Chain Solutions. \u00abSin embargo, dado que como proveedor de servicios de gesti\u00f3n de la cadena de suministro y comercio electr\u00f3nico realizamos servicios en los que no podemos evitar la generaci\u00f3n de gases de efecto invernadero al 100%, aplicaremos medidas de compensaci\u00f3n para el 50% restante.\u00bb<\/p>\n<h5>Medidas de sostenibilidad tambi\u00e9n en otras ubicaciones<\/h5>\n<p class=\"FunktionAbt\">Tambi\u00e9n se han implementado amplias medidas de sostenibilidad en otras ubicaciones que contribuyen a alcanzar los objetivos clim\u00e1ticos. Adem\u00e1s del suministro de electricidad 100% verde y la transici\u00f3n a iluminaci\u00f3n LED, se utilizan, por ejemplo, modernos sistemas de recuperaci\u00f3n de calor con compresores de aire para reducir continuamente el consumo de gas para calefacci\u00f3n. Otras ahorros se logran mediante filtros de aire adaptados, reducciones nocturnas de temperatura dentro de las \u00e1reas de almacenamiento y la conexi\u00f3n de ventanas y sistemas de aire acondicionado, que se apagan tan pronto como se abre una ventana. Adem\u00e1s, se han instalado centrales el\u00e9ctricas de cogeneraci\u00f3n eficientes en energ\u00eda como tecnolog\u00eda de transici\u00f3n y sistemas de geotermia sostenibles en algunas ubicaciones. \u00abAl optimizar, observamos muy de cerca qu\u00e9 tecnolog\u00edas y medidas verdes son adecuadas para la ubicaci\u00f3n y se pueden implementar de manera \u00f3ptima all\u00ed\u00bb, dice Olaf Pack, Vicepresidente de Bienes Ra\u00edces en Arvato Supply Chain Solutions. \u00abPorque estos proyectos no solo contribuyen a alcanzar nuestros objetivos de protecci\u00f3n clim\u00e1tica, sino que tambi\u00e9n hacen una importante contribuci\u00f3n a la promoci\u00f3n de la sostenibilidad en las respectivas comunidades.\u00bb<\/p>\n<p>Foto: \u00a9 Arvato Supply Chain Solutions<\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Arvato Supply Chain Solutions invierte masivamente en tecnolog\u00edas ecol\u00f3gicas como parte de su estrategia de sostenibilidad. Hasta ahora, el proveedor internacional de servicios de cadena de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1560,1561],"tags":[],"class_list":["post-26590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Arvato Supply Chain Solutions invierte masivamente en tecnolog\u00edas ecol\u00f3gicas como parte de su estrategia de sostenibilidad. Hasta ahora, el proveedor internacional de servicios de cadena de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-18T13:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1274\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Arvato Supply Chain instala nueva planta solar en Gennep\",\"datePublished\":\"2022-01-18T13:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/\"},\"wordCount\":616,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_18.1.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/\",\"name\":\"Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_18.1.22.jpg\",\"datePublished\":\"2022-01-18T13:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_18.1.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Arvato_18.1.22.jpg\",\"width\":1274,\"height\":714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/18\\\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arvato Supply Chain instala nueva planta solar en Gennep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/","og_locale":"es_ES","og_type":"article","og_title":"Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24","og_description":"Arvato Supply Chain Solutions invierte masivamente en tecnolog\u00edas ecol\u00f3gicas como parte de su estrategia de sostenibilidad. Hasta ahora, el proveedor internacional de servicios de cadena de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-18T13:00:01+00:00","og_image":[{"width":1274,"height":714,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/"},"author":{"name":"","@id":""},"headline":"Arvato Supply Chain instala nueva planta solar en Gennep","datePublished":"2022-01-18T13:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/"},"wordCount":616,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/","url":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/","name":"Arvato Supply Chain instala nueva planta solar en Gennep - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg","datePublished":"2022-01-18T13:00:01+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Arvato_18.1.22.jpg","width":1274,"height":714},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/18\/arvato-supply-chain-instala-nueva-planta-solar-en-gennep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Arvato Supply Chain instala nueva planta solar en Gennep"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/26590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=26590"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/26590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/11255"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=26590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=26590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=26590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}