{"id":26508,"date":"2022-01-13T19:49:17","date_gmt":"2022-01-13T18:49:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/"},"modified":"2022-01-13T19:49:17","modified_gmt":"2022-01-13T18:49:17","slug":"transporeon-adquiere-supplystack-y-nexogen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/","title":{"rendered":"Transporeon adquiere SupplyStack y Nexogen"},"content":{"rendered":"<h5><strong>Transporeon <\/strong><strong> anuncia dos adquisiciones con las que la empresa sigue ampliando las capacidades de su red en el marco de su estrategia de crecimiento internacional. A trav\u00e9s de la integraci\u00f3n de SupplyStack, Transporeon introduce funciones multimodales y de carga parcial en su plataforma global de gesti\u00f3n del transporte y, mediante la adquisici\u00f3n de Nexogen, ampl\u00eda la oferta para los transportistas.<\/strong><\/h5>\n<p>(Neu-Ulm) Con la adquisici\u00f3n de SupplyStack y Nexogen, los clientes de Transporeon se benefician una vez m\u00e1s de que los servicios de la plataforma de gesti\u00f3n del transporte se ofrecen de manera modular. Las nuevas funciones se integran directamente en la red de Transporeon. De esta manera, Transporeon ofrece soluciones f\u00e1ciles de usar para la optimizaci\u00f3n de procesos de transporte, adaptadas a la TI interna de los clientes, as\u00ed como a sus respectivos sistemas de planificaci\u00f3n de recursos empresariales (ERP) y de gesti\u00f3n del transporte (TMS). De este modo, Transporeon permite a sus clientes operar con \u00e9xito en un mercado que exige cada vez m\u00e1s sostenibilidad, eficiencia temporal y menores costos.<\/p>\n<h5><strong>Transporeon adquiere SupplyStack <\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16726 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_2.jpg\" alt=\"\" width=\"1316\" height=\"684\" \/>Despu\u00e9s de la adquisici\u00f3n de Logit One, un especialista en planificaci\u00f3n multimodal y visibilidad del transporte mar\u00edtimo en diciembre de 2021, Transporeon ahora integra SupplyStack en su plataforma de gesti\u00f3n del transporte. De esta manera, Transporeon refuerza su competencia en la planificaci\u00f3n de transportes multimodales y de carga parcial.<\/p>\n<p>Los clientes de Transporeon obtienen acceso a una herramienta de planificaci\u00f3n y ejecuci\u00f3n que puede procesar cargas parciales en todos los modos de transporte. As\u00ed, Transporeon optimiza la planificaci\u00f3n del transporte, la adjudicaci\u00f3n de pedidos y la ejecuci\u00f3n. Los procesos se automatizan y se vuelven m\u00e1s eficientes.<\/p>\n<p>Despu\u00e9s de una fase de integraci\u00f3n, los clientes de SupplyStack obtendr\u00e1n acceso a la red de transportistas de Transporeon, servicios de plataforma, compra de carga y gesti\u00f3n de tarifas, as\u00ed como servicios de asignaci\u00f3n de carga spot, facturaci\u00f3n de carga y auditor\u00eda.<\/p>\n<p>Adem\u00e1s, los clientes se benefician de la integraci\u00f3n de los servicios de visibilidad en tiempo real (RTV) de Transporeon Sixfold. Esto significa que los transportistas y cargadores no necesitan utilizar una aplicaci\u00f3n separada para el seguimiento de env\u00edos. La integraci\u00f3n de las funciones en una aplicaci\u00f3n central permite a las empresas atender mejor a sus clientes y aumentar su propia eficiencia, sentando as\u00ed las bases para una cadena de suministro m\u00e1s sostenible.<\/p>\n<h5><strong>Demanda de transparencia en la cadena de suministro<\/strong><\/h5>\n<p>El CEO de Transporeon, Stephan Sieber, comenta: \u00abEn la cadena de suministro existe una creciente necesidad de mejorar la transparencia en las entregas, reducir costos y al mismo tiempo hacer el transporte de mercanc\u00edas m\u00e1s sostenible. La expansi\u00f3n de nuestra plataforma con herramientas para la planificaci\u00f3n y ejecuci\u00f3n de transportes multimodales y de carga parcial a trav\u00e9s de la adquisici\u00f3n de SupplyStack otorga a nuestros clientes la flexibilidad necesaria para alcanzar estos objetivos\u00bb.<\/p>\n<p>Nick Poels, fundador y CEO de SupplyStack, a\u00f1ade: \u00abPor separado somos fuertes, pero juntos somos m\u00e1s fuertes. Esta adquisici\u00f3n es un hito para nuestra misi\u00f3n de revolucionar el transporte de carga. La combinaci\u00f3n de las soluciones de gesti\u00f3n del transporte de SupplyStack con la red de Transporeon permitir\u00e1 a nuestros clientes beneficiarse de nuestras soluciones, en todos los modos de transporte y en cadenas de suministro internacionales, as\u00ed como en carreteras nacionales. Por lo tanto, estamos emocionados de ser parte de la familia Transporeon. Aqu\u00ed, nuestros clientes de diversas industrias pueden gestionar sus procesos log\u00edsticos en una verdadera red\u00bb.<\/p>\n<h5><strong>Transporeon adquiere Nexogen <\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-16730\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_1.jpg\" alt=\"\" width=\"1024\" height=\"533\" \/>Para apoyar a los transportistas en la gesti\u00f3n de sus flotas, Transporeon adquiere Nexogen. La empresa de Software como Servicio (SaaS) est\u00e1 especializada en la planificaci\u00f3n de transporte basada en IA en el transporte por carretera, con la que los transportistas y proveedores de log\u00edstica pueden mejorar la utilizaci\u00f3n de sus veh\u00edculos. Para ello, el software optimiza la asignaci\u00f3n de capacidad disponible a los pedidos y coordina conductores y rutas.<\/p>\n<p>Hoy en d\u00eda, Transporeon ya ofrece un amplio portafolio de servicios para transportistas y proveedores de log\u00edstica. Los servicios de Transporeon en este \u00e1mbito abarcan desde inteligencia de mercado, RTV en transporte mar\u00edtimo, a\u00e9reo y por carretera, hasta compra de carga aut\u00f3noma y gesti\u00f3n de documentos. A trav\u00e9s de la adquisici\u00f3n de Nexogen y la integraci\u00f3n del planificador de IA y del operador de IA, Transporeon refuerza a\u00fan m\u00e1s su completo portafolio de servicios para transportistas.<\/p>\n<ul>\n<li>El planificador de IA de Nexogen se puede vincular con soluciones TMS existentes y apoya la utilizaci\u00f3n \u00f3ptima de los medios de transporte, emparejando pedidos con camiones y conductores en funci\u00f3n de datos. El motor del planificador de IA planifica de manera proactiva y tambi\u00e9n tiene en cuenta datos del mercado spot para garantizar una utilizaci\u00f3n \u00f3ptima de la flota.<\/li>\n<li>El operador de IA de Nexogen ayuda a gestionar flotas de manera m\u00e1s eficiente en funci\u00f3n de telem\u00e1tica y datos en tiempo real. Adem\u00e1s de una herramienta de planificaci\u00f3n de rutas eficiente, tambi\u00e9n ofrece informaci\u00f3n en tiempo real sobre la ejecuci\u00f3n del transporte. El operador de IA utiliza datos en bruto como el tiempo de conducci\u00f3n restante o el nivel de combustible para calcular la ruta en funci\u00f3n de t\u00faneles, ferris, \u00e1reas de descanso y estaciones de servicio, y predecir tiempos de llegada precisos. El operador de IA siempre tiene en cuenta las regulaciones de la UE aplicables.<\/li>\n<\/ul>\n<h5><strong>Los transportistas reciben ofertas spot<\/strong><\/h5>\n<p>Los transportistas que ya trabajan con Nexogen podr\u00e1n recibir en el futuro ofertas spot de Transporeon y as\u00ed asumir cargas adicionales. Adem\u00e1s, podr\u00e1n encontrar a trav\u00e9s de la plataforma de Transporeon subcontratistas que transporten cargas excedentes para ellos.<\/p>\n<p>Dada la ineficiencia de hasta el 30% en el transporte por carretera europeo, la escasez de conductores y los cada vez mayores objetivos de sostenibilidad, los transportistas y cargadores deben trabajar de manera m\u00e1s eficiente, reduciendo tanto los viajes vac\u00edos como los tiempos de espera no rentables.<\/p>\n<p>Stephan Sieber, CEO de Transporeon, comenta: <em>\u00ab<\/em>La integraci\u00f3n de Nexogen en nuestra plataforma de gesti\u00f3n del transporte ayudar\u00e1 a los transportistas a utilizar mejor sus activos log\u00edsticos y a gestionar la complejidad. Esto es especialmente relevante en relaci\u00f3n con el paquete de movilidad de la UE. El paquete garantiza una competencia justa en el mercado interior europeo y protege a los conductores mediante reglas claras. Al mismo tiempo, introduce nuevas regulaciones que los conductores deben tener en cuenta. Para trabajar con \u00e9xito dentro de las nuevas condiciones, se necesitan soluciones inteligentes. Los servicios impulsados por IA de Nexogen ayudan a los operadores de flotas a considerar toda la informaci\u00f3n y las reglas necesarias en la planificaci\u00f3n del transporte\u00bb.<\/p>\n<h5><strong>Planificaci\u00f3n inteligente y automatizada<\/strong><\/h5>\n<p>\u00abNuestro objetivo es utilizar datos para aprovechar el potencial de la log\u00edstica a trav\u00e9s de una planificaci\u00f3n y optimizaci\u00f3n inteligentes y automatizadas. Al integrar los recursos de Nexogen en el amplio portafolio de Transporeon, podemos impulsar la digitalizaci\u00f3n y as\u00ed aumentar la eficiencia. Al mismo tiempo, reducimos de esta manera las emisiones de CO2 en cada transporte de carga. Por lo tanto, estamos emocionados de ser parte del ecosistema de Transporeon y de la red con m\u00e1s de 130,000 transportistas\u00bb, enfatiza Andr\u00e1s Kov\u00e1cs, CEO de Nexogen.<\/p>\n<p>Gr\u00e1ficos: \u00a9 Transporeon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transporeon anuncia dos adquisiciones con las que la empresa sigue ampliando las capacidades de su red en el marco de su estrategia de crecimiento internacional. A<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11305,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-26508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transporeon adquiere SupplyStack y Nexogen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transporeon adquiere SupplyStack y Nexogen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Transporeon anuncia dos adquisiciones con las que la empresa sigue ampliando las capacidades de su red en el marco de su estrategia de crecimiento internacional. A [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-13T18:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"727\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Transporeon adquiere SupplyStack y Nexogen\",\"datePublished\":\"2022-01-13T18:49:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/\"},\"wordCount\":1280,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_13.1.22_3.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/\",\"name\":\"Transporeon adquiere SupplyStack y Nexogen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_13.1.22_3.jpg\",\"datePublished\":\"2022-01-13T18:49:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_13.1.22_3.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_13.1.22_3.jpg\",\"width\":1296,\"height\":727},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2022\\\/01\\\/13\\\/transporeon-adquiere-supplystack-y-nexogen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transporeon adquiere SupplyStack y Nexogen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transporeon adquiere SupplyStack y Nexogen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/","og_locale":"es_ES","og_type":"article","og_title":"Transporeon adquiere SupplyStack y Nexogen - Loginfo24","og_description":"Transporeon anuncia dos adquisiciones con las que la empresa sigue ampliando las capacidades de su red en el marco de su estrategia de crecimiento internacional. A [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-13T18:49:17+00:00","og_image":[{"width":1296,"height":727,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/"},"author":{"name":"","@id":""},"headline":"Transporeon adquiere SupplyStack y Nexogen","datePublished":"2022-01-13T18:49:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/"},"wordCount":1280,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/","url":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/","name":"Transporeon adquiere SupplyStack y Nexogen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg","datePublished":"2022-01-13T18:49:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_13.1.22_3.jpg","width":1296,"height":727},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2022\/01\/13\/transporeon-adquiere-supplystack-y-nexogen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Transporeon adquiere SupplyStack y Nexogen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/26508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=26508"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/26508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/11305"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=26508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=26508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=26508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}