{"id":25994,"date":"2021-06-07T20:11:45","date_gmt":"2021-06-07T18:11:45","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/"},"modified":"2025-12-15T13:05:09","modified_gmt":"2025-12-15T12:05:09","slug":"provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/","title":{"rendered":"Provadis lanza un programa de estudios en log\u00edstica con BGL"},"content":{"rendered":"<p>La Universidad Provadis y la Asociaci\u00f3n Federal de Transporte de Mercanc\u00edas, Log\u00edstica y Eliminaci\u00f3n (BGL) e.V. \u2013 ambas de Fr\u00e1ncfort del Meno \u2013 han dise\u00f1ado conjuntamente un nuevo programa de estudios dual en log\u00edstica. A trav\u00e9s de la cooperaci\u00f3n entre la Universidad Provadis y el BGL, se implementa un nuevo y \u00fanico concepto de aprendizaje en el programa de Gesti\u00f3n de Transporte y Log\u00edstica (Bachelor of Science).<\/p>\n<p>(Fr\u00e1ncfort del Meno) Juntos, la Universidad Provadis y la Asociaci\u00f3n Federal de Transporte de Mercanc\u00edas, Log\u00edstica y Eliminaci\u00f3n (BGL) e.V. quieren formar a los empleados de hoy para las demandas del ma\u00f1ana, equip\u00e1ndolos con el conocimiento te\u00f3rico y las herramientas pr\u00e1cticas necesarias para enfrentar los desaf\u00edos actuales y futuros en una econom\u00eda global y digitalizada.<\/p>\n<p>Durante sus estudios, los estudiantes trabajan regularmente en sus empresas y son instruidos principalmente en l\u00ednea - en aulas virtuales, pero tambi\u00e9n en unidades de aprendizaje autodirigidas - as\u00ed como en diversos eventos presenciales, siguiendo el concepto probado de Provadis durante m\u00e1s de diez a\u00f1os. La Universidad Provadis emplea a profesores y profesoras propios, orientados a la pr\u00e1ctica, pero tambi\u00e9n el BGL, como asociaci\u00f3n l\u00edder del sector de transporte y log\u00edstica en Alemania, proporciona docentes y asegura as\u00ed la importante y pionera conexi\u00f3n con los temas actuales de log\u00edstica, log\u00edstica de informaci\u00f3n o pol\u00edtica a nivel federal y europeo. A trav\u00e9s del dise\u00f1o de las clases, los estudiantes adquieren una mezcla \u00fanica de conocimientos te\u00f3ricos fundamentales y referencias pr\u00e1cticas, impartidas por docentes y profesores que est\u00e1n muy familiarizados con la pr\u00e1ctica.<\/p>\n<h5><strong>Formar para los desaf\u00edos del futuro<\/strong><\/h5>\n<p>\u00abEl objetivo de la Universidad Provadis y el BGL es, junto con las empresas asociadas y la industria, formar y preparar a los participantes del programa para los desaf\u00edos actuales y futuros\u00bb, afirma la decana de Ciencias Econ\u00f3micas de la Universidad Provadis, Prof. Dr. Ursula Bicher-Otto.<\/p>\n<p>\u00abLos contenidos impartidos abarcan desde la econom\u00eda empresarial y la econom\u00eda general o la estad\u00edstica, hasta los fundamentos y condiciones del transporte y la log\u00edstica, la gesti\u00f3n de la cadena de suministro (SCM) o la contabilidad de costos en log\u00edstica, as\u00ed como la digitalizaci\u00f3n, la Industria 4.0 y las condiciones y proyectos pol\u00edticos actuales y planificados en Bruselas y Berl\u00edn. Los temas de innovaci\u00f3n y \u00e9tica completan el concepto de aprendizaje\u00bb, a\u00f1ade el director del programa, Prof. Dr. Peter Holm. El programa se ubica en la Facultad de Ciencias Econ\u00f3micas de la Universidad Provadis.<\/p>\n<h5><strong>Parte de las clases en ingl\u00e9s<\/strong><\/h5>\n<p>Una parte de las clases est\u00e1 dise\u00f1ada en ingl\u00e9s para formar a los estudiantes para un mercado log\u00edstico internacional. El inicio del programa est\u00e1 previsto para el oto\u00f1o de 2021. Inicialmente, Fr\u00e1ncfort del Meno est\u00e1 previsto como ubicaci\u00f3n para los eventos presenciales.<\/p>\n<p>\u00abOtra ventaja: gracias a la estructura federal del BGL con sus asociaciones estatales y su propia oficina internacional en Bruselas, as\u00ed como las cooperaciones con Francia y los pa\u00edses escandinavos, se pueden habilitar en cualquier momento otras ubicaciones de estudio si es necesario. Adem\u00e1s, la cooperativa de transporte por carretera (SVG) y el asegurador del sector KRAVAG son otros socios fuertes del BGL para futuras adaptaciones y desarrollos\u00bb, enfatiza Prof. Dr. Dirk Engelhardt del BGL.<\/p>\n<p>Se planea la creaci\u00f3n de un consejo empresarial para orientar el programa de estudios de manera continua a las necesidades de la pr\u00e1ctica, en di\u00e1logo mutuo con representantes de la industria log\u00edstica y la industria. Desde el BGL, su presidente, Prof. Dr. Dirk Engelhardt, aportar\u00e1 sus ideas. \u00abEsperamos con inter\u00e9s el di\u00e1logo con las empresas del sector log\u00edstico, la econom\u00eda cargadora y especialmente con los estudiantes\u00bb, enfatiza Prof. Dr. Ursula Bicher-Otto.<\/p>\n<h5><strong>BGL<\/strong><\/h5>\n<p>El BGL es la asociaci\u00f3n l\u00edder para el transporte de mercanc\u00edas por carretera, log\u00edstica y eliminaci\u00f3n en Alemania, con sede en Fr\u00e1ncfort del Meno. Desde 1947, representa los intereses profesionales de alrededor de 7,000 empresas organizadas en sus asociaciones estatales. Estas se dedican principalmente a las \u00e1reas de transporte de mercanc\u00edas por carretera, log\u00edstica, expedici\u00f3n, almacenamiento y eliminaci\u00f3n.<\/p>\n<h5><strong>Universidad Provadis<\/strong><\/h5>\n<p>La Universidad Provadis es una empresa subsidiaria de Provadis Partner f\u00fcr Bildung und Beratung GmbH. En la universidad, fundada en 2001, estudian m\u00e1s de 1,200 estudiantes en programas de estudios duales y de formaci\u00f3n continua con t\u00edtulos de Bachelor y Master reconocidos internacionalmente. La universidad agrupa sus actividades interdisciplinarias en el \u00e1rea de investigaci\u00f3n y proyectos en el Centro para la Industria y la Sostenibilidad.<\/p>\n<h4><a href=\"https:\/\/www.provadis-hochschule.de\/bachelor-studiengaenge\/wirtschaftswissenschaften\/bachelor-transport-und-logistikmanagement.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Informaci\u00f3n sobre el programa de estudios con posibilidad de inscripci\u00f3n<\/strong><\/a><\/h4>\n<p>Foto: \u00a9 Provadis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Provadis y la Asociaci\u00f3n Federal de Transporte de Mercanc\u00edas, Log\u00edstica y Eliminaci\u00f3n (BGL) e.V. \u2013 ambas de Fr\u00e1ncfort del Meno \u2013 han dise\u00f1ado conjuntamente<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-25994","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Universidad Provadis y la Asociaci\u00f3n Federal de Transporte de Mercanc\u00edas, Log\u00edstica y Eliminaci\u00f3n (BGL) e.V. \u2013 ambas de Fr\u00e1ncfort del Meno \u2013 han dise\u00f1ado conjuntamente [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T18:11:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:05:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Provadis lanza un programa de estudios en log\u00edstica con BGL\",\"datePublished\":\"2021-06-07T18:11:45+00:00\",\"dateModified\":\"2025-12-15T12:05:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/\"},\"wordCount\":827,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/\",\"name\":\"Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-06-07T18:11:45+00:00\",\"dateModified\":\"2025-12-15T12:05:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/06\\\/07\\\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provadis lanza un programa de estudios en log\u00edstica con BGL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/","og_locale":"es_ES","og_type":"article","og_title":"Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24","og_description":"La Universidad Provadis y la Asociaci\u00f3n Federal de Transporte de Mercanc\u00edas, Log\u00edstica y Eliminaci\u00f3n (BGL) e.V. \u2013 ambas de Fr\u00e1ncfort del Meno \u2013 han dise\u00f1ado conjuntamente [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-07T18:11:45+00:00","article_modified_time":"2025-12-15T12:05:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/"},"author":{"name":"","@id":""},"headline":"Provadis lanza un programa de estudios en log\u00edstica con BGL","datePublished":"2021-06-07T18:11:45+00:00","dateModified":"2025-12-15T12:05:09+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/"},"wordCount":827,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/","url":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/","name":"Provadis lanza un programa de estudios en log\u00edstica con BGL - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-06-07T18:11:45+00:00","dateModified":"2025-12-15T12:05:09+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/06\/07\/provadis-lanza-un-programa-de-estudios-en-logistica-con-bgl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Provadis lanza un programa de estudios en log\u00edstica con BGL"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=25994"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25994\/revisions"}],"predecessor-version":[{"id":47674,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25994\/revisions\/47674"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=25994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=25994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=25994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}