{"id":25826,"date":"2021-05-31T20:08:47","date_gmt":"2021-05-31T18:08:47","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/"},"modified":"2025-12-15T13:04:21","modified_gmt":"2025-12-15T12:04:21","slug":"krummen-kerzers-con-tractor-electrico-de-futuricum","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/","title":{"rendered":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum"},"content":{"rendered":"<p>El lema de la empresa de transporte Krummen Kerzers AG de Suiza es &#8216;Hacemos m\u00e1s&#8217;. Una promesa que tambi\u00e9n se refiere a la protecci\u00f3n del medio ambiente, como demuestra de manera contundente el especialista en log\u00edstica con la adquisici\u00f3n de un tractor el\u00e9ctrico de Futuricum.<\/p>\n<p>(Kerzers) \u00abLas empresas tienen una responsabilidad especial en la protecci\u00f3n del clima. Queremos liderar el camino y reemplazar gradualmente los combustibles f\u00f3siles. Para cumplir con esta obligaci\u00f3n social, utilizamos todos los medios y formas posibles para mantener nuestra huella de CO2 lo m\u00e1s peque\u00f1a posible\u00bb, dice Peter Krummen, socio gerente de Krummen Kerzers AG. Por ello, el especialista suizo en log\u00edstica ha estado apostando durante a\u00f1os por conceptos de uso de tecnolog\u00edas de propulsi\u00f3n alternativas. As\u00ed, la empresa, adem\u00e1s de varios camiones de gas natural licuado (GNL), tambi\u00e9n cuenta con su propia estaci\u00f3n de servicio de GNL y un veh\u00edculo cisterna propio. La entrada en la movilidad el\u00e9ctrica marca para Krummen Kerzers el siguiente paso l\u00f3gico hacia la neutralidad clim\u00e1tica.<\/p>\n<p>El cami\u00f3n el\u00e9ctrico de la marca Futuricum, ahora adquirido, es el tercero en Suiza y se basa en la serie FH de Volvo, alcanzando una autonom\u00eda de 500 kil\u00f3metros con sus bater\u00edas de 900 kWh. El veh\u00edculo se carga completamente en cuatro horas. Si se utiliza electricidad de fuentes renovables, se pueden ahorrar anualmente 140 toneladas de CO2 con solo un cami\u00f3n el\u00e9ctrico. Para Krummen, la adquisici\u00f3n del Futuricum \u2013 cuyo precio de compra es varias veces superior al de un tractor di\u00e9sel convencional \u2013 no solo es una cuesti\u00f3n de protecci\u00f3n del medio ambiente, sino tambi\u00e9n una inversi\u00f3n en la competitividad futura.<\/p>\n<div id=\"attachment_11723\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11723\" class=\"size-large wp-image-11723\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg\" alt=\"\" width=\"1024\" height=\"590\" \/><p id=\"caption-attachment-11723\" class=\"wp-caption-text\">Tractor Futuricum de Krummen Kerzers<\/p><\/div>\n<h5><strong>Inversi\u00f3n en competitividad futura<\/strong><\/h5>\n<p>Esto tambi\u00e9n lo confirma Christian Bach, jefe del departamento de sistemas de propulsi\u00f3n de veh\u00edculos en el Instituto Federal de Materiales y Pruebas (Empa): \u00abLa descarbonizaci\u00f3n del transporte de mercanc\u00edas ser\u00e1 un gran desaf\u00edo para la industria en los pr\u00f3ximos a\u00f1os. La clave es la transici\u00f3n a la energ\u00eda renovable. Dependiendo de la aplicaci\u00f3n, se ofrecen diferentes conceptos de propulsi\u00f3n. Donde sea posible, el uso directo de electricidad renovable en camiones el\u00e9ctricos de bater\u00eda es el enfoque correcto.\u00bb<\/p>\n<p>En este contexto, la estrategia de flota de Krummen Kerzers se mantiene deliberadamente abierta a la tecnolog\u00eda. Peter Krummen: \u00abNo buscamos un \u00fanico reemplazo para el propulsor di\u00e9sel. Cada tecnolog\u00eda debe utilizarse donde genere el mayor beneficio posible.\u00bb El cami\u00f3n articulado Futuricum ya ofrece un amplio espectro de \u00e1reas de aplicaci\u00f3n con su autonom\u00eda y se espera que se utilice en el transporte de distribuci\u00f3n para la Romand\u00eda a partir de diciembre.<\/p>\n<p>Foto del t\u00edtulo: \u00a9 Krummen \/ <strong><em>Subt\u00edtulo de la imagen:<\/em><\/strong><em> Hans (izquierda) y Peter Krummen frente al nuevo tractor Futuricum<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lema de la empresa de transporte Krummen Kerzers AG de Suiza es &#8216;Hacemos m\u00e1s&#8217;. Una promesa que tambi\u00e9n se refiere a la protecci\u00f3n del medio<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-25826","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El lema de la empresa de transporte Krummen Kerzers AG de Suiza es &#8216;Hacemos m\u00e1s&#8217;. Una promesa que tambi\u00e9n se refiere a la protecci\u00f3n del medio [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T18:08:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:04:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum\",\"datePublished\":\"2021-05-31T18:08:47+00:00\",\"dateModified\":\"2025-12-15T12:04:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Krummen_31.5.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/\",\"name\":\"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Krummen_31.5.21.jpg\",\"datePublished\":\"2021-05-31T18:08:47+00:00\",\"dateModified\":\"2025-12-15T12:04:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Krummen_31.5.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Krummen_31.5.21.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/31\\\/krummen-kerzers-con-tractor-electrico-de-futuricum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/","og_locale":"es_ES","og_type":"article","og_title":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24","og_description":"El lema de la empresa de transporte Krummen Kerzers AG de Suiza es &#8216;Hacemos m\u00e1s&#8217;. Una promesa que tambi\u00e9n se refiere a la protecci\u00f3n del medio [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-31T18:08:47+00:00","article_modified_time":"2025-12-15T12:04:21+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/"},"author":{"name":"","@id":""},"headline":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum","datePublished":"2021-05-31T18:08:47+00:00","dateModified":"2025-12-15T12:04:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/","url":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/","name":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg","datePublished":"2021-05-31T18:08:47+00:00","dateModified":"2025-12-15T12:04:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Krummen_31.5.21.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/31\/krummen-kerzers-con-tractor-electrico-de-futuricum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Krummen Kerzers con tractor el\u00e9ctrico de Futuricum"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=25826"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25826\/revisions"}],"predecessor-version":[{"id":47346,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25826\/revisions\/47346"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=25826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=25826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=25826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}