{"id":25354,"date":"2021-05-10T18:12:17","date_gmt":"2021-05-10T16:12:17","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/"},"modified":"2025-12-15T13:01:57","modified_gmt":"2025-12-15T12:01:57","slug":"geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/","title":{"rendered":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus"},"content":{"rendered":"<p>Cadena de suministro eficiente en la lucha contra Covid-19: El grupo Geis, que opera a nivel internacional, se encarga de la importaci\u00f3n y distribuci\u00f3n completa de pruebas r\u00e1pidas de coronavirus y mascarillas para una empresa de Baden-W\u00fcrttemberg. La sede principal es la de Geis Air + Sea GmbH en K\u00fcrnach, cerca de W\u00fcrzburg.<\/p>\n<p>(K\u00fcrnach) En los \u00faltimos meses, el equipo ha importado m\u00e1s de 3,5 millones de pruebas y dos millones de mascarillas desde China a Alemania y las ha entregado a los clientes, con una tendencia en aumento. El cliente de las importaciones se especializa exclusivamente en la venta de equipos de protecci\u00f3n y pruebas r\u00e1pidas de Covid-19. Estos se entregan a consultorios m\u00e9dicos, farmacias, centros de pruebas de coronavirus y otros clientes que necesitan urgentemente estos productos esenciales. Por lo tanto, el proyecto se centra principalmente en la rapidez y la fiabilidad.<\/p>\n<h5><strong>En tres d\u00edas en el destinatario<\/strong><\/h5>\n<p>\u00abPara las importaciones de pruebas y mascarillas hemos desarrollado una cadena de suministro altamente eficiente\u00bb, dice Jonas Schmuck, responsable del proyecto en Geis Air + Sea. \u00abDe esta manera, conseguimos entregar la mercanc\u00eda en un plazo de tres d\u00edas desde el productor en China hasta el cliente final.\u00bb Para ello, Geis recibe informaci\u00f3n sobre cu\u00e1ndo y qu\u00e9 mercanc\u00eda puede ser recogida de los fabricantes en Pek\u00edn, Shangh\u00e1i, Wuhan y Cant\u00f3n, y a d\u00f3nde debe ser entregada. Geis reserva o fleta inmediatamente los vuelos de carga y encarga a su socio chino la recogida. Despu\u00e9s del control aduanero en China, la mercanc\u00eda se dirige a \u00c1msterdam. A las autoridades en el aeropuerto de \u00c1msterdam, Geis ya ha enviado previamente los datos necesarios para la aduana, de modo que la mercanc\u00eda puede ser cargada r\u00e1pidamente en el lugar y llevada a K\u00fcrnach. \u00abPrincipalmente utilizamos camiones que funcionan con gas natural licuado m\u00e1s ecol\u00f3gico en lugar de di\u00e9sel\u00bb, explica Jonas Schmuck. \u00abPara no perder tiempo valioso, organizamos las rutas durante las prohibiciones de circulaci\u00f3n de camiones los domingos y festivos con veh\u00edculos de transporte peque\u00f1o.\u00bb<\/p>\n<h5><strong>Geis tambi\u00e9n entrega el mismo d\u00eda y los s\u00e1bados<\/strong><\/h5>\n<p>En la terminal de transbordo de K\u00fcrnach, Geis verifica la mercanc\u00eda para asegurar su integridad y luego se env\u00eda directamente a los clientes. Para peque\u00f1as cantidades, Geis utiliza servicios de paqueter\u00eda, para mercanc\u00edas en paletas sus propios servicios expr\u00e9s de carga consolidada, y para grandes cantidades o solicitudes especiales, Geis entrega la mercanc\u00eda directamente a los clientes. \u00abSi es necesario, entregamos el mismo d\u00eda o el s\u00e1bado\u00bb, dice Jonas Schmuck. \u00abLo decisivo es que todo funcione de manera r\u00e1pida y fluida.\u00bb<br \/>Foto: \u00a9 Geis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadena de suministro eficiente en la lucha contra Covid-19: El grupo Geis, que opera a nivel internacional, se encarga de la importaci\u00f3n y distribuci\u00f3n completa de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1561],"tags":[],"class_list":["post-25354","post","type-post","status-publish","format-standard","hentry","category-air-freight","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Cadena de suministro eficiente en la lucha contra Covid-19: El grupo Geis, que opera a nivel internacional, se encarga de la importaci\u00f3n y distribuci\u00f3n completa de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-10T16:12:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:01:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus\",\"datePublished\":\"2021-05-10T16:12:17+00:00\",\"dateModified\":\"2025-12-15T12:01:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/\"},\"wordCount\":481,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/\",\"name\":\"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-10T16:12:17+00:00\",\"dateModified\":\"2025-12-15T12:01:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/10\\\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24","og_description":"Cadena de suministro eficiente en la lucha contra Covid-19: El grupo Geis, que opera a nivel internacional, se encarga de la importaci\u00f3n y distribuci\u00f3n completa de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-10T16:12:17+00:00","article_modified_time":"2025-12-15T12:01:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/"},"author":{"name":"","@id":""},"headline":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus","datePublished":"2021-05-10T16:12:17+00:00","dateModified":"2025-12-15T12:01:57+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/"},"wordCount":481,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Air Freight","Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/","url":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/","name":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-05-10T16:12:17+00:00","dateModified":"2025-12-15T12:01:57+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/10\/geis-proporciona-una-solucion-logistica-integral-para-pruebas-rapidas-de-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Geis proporciona una soluci\u00f3n log\u00edstica integral para pruebas r\u00e1pidas de coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=25354"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25354\/revisions"}],"predecessor-version":[{"id":46422,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25354\/revisions\/46422"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=25354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=25354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=25354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}