{"id":25288,"date":"2021-05-06T18:26:51","date_gmt":"2021-05-06T16:26:51","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/"},"modified":"2025-12-15T13:01:37","modified_gmt":"2025-12-15T12:01:37","slug":"el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/","title":{"rendered":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal"},"content":{"rendered":"<p>La Sociedad Portuaria de L\u00fcbeck (LHG) se est\u00e1 preparando para un aumento en los transportes ferroviarios. Por esta raz\u00f3n, la LHG ha elaborado un plan maestro dentro del grupo empresarial. El enfoque est\u00e1 en la infraestructura y los procesos en el Skandinavienkai para poder recibir m\u00e1s transportes intermodales.<\/p>\n<p>(L\u00fcbeck) El mercado intermodal est\u00e1 creciendo. L\u00fcbeck, con 50 salidas semanales hacia centros industriales alemanes e italianos, es algo as\u00ed como un puente intermodal en el Mar B\u00e1ltico. Para fortalecer a\u00fan m\u00e1s esta posici\u00f3n, la Sociedad Portuaria de L\u00fcbeck (LHG) ha creado un plan maestro dentro de su grupo empresarial.<\/p>\n<p>El enfoque est\u00e1 en la infraestructura y los procesos en el Skandinavienkai. Antes del verano, la LHG estar\u00e1 en condiciones de recibir m\u00e1s transportes intermodales. Para ello, varias \u00e1reas de la empresa est\u00e1n trabajando en red con un conjunto de medidas.<\/p>\n<h5><strong>Ampliaci\u00f3n de capacidades en la terminal de Travem\u00fcnde<\/strong><\/h5>\n<p>Principalmente se trata de ampliar las capacidades de la terminal de Travem\u00fcnde en el transporte ferroviario. Las cantidades hab\u00edan aumentado recientemente debido al cierre de los transportes de remolques por ferrocarril a trav\u00e9s de Dinamarca. Adem\u00e1s, la reciente conexi\u00f3n con el Mega-Hub de Lehrte deber\u00eda proporcionar nuevos impulsos en el futuro. Las cantidades en el puerto tambi\u00e9n est\u00e1n evolucionando de manera muy positiva. En los primeros tres meses, el volumen de carga en la LHG ha aumentado en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior.<\/p>\n<p>En el centro de las consideraciones est\u00e1 la terminal intermodal de la filial de la LHG, Baltic Rail Gate (BRG). El equipo est\u00e1 trabajando en un sistema de tres turnos y, por lo tanto, tambi\u00e9n est\u00e1 operativo durante la noche. Adem\u00e1s, los planes para extender las v\u00edas existentes de 600 metros a 750 metros est\u00e1n casi completos. Se espera que se realicen lo antes posible.<\/p>\n<h5><strong>Operaci\u00f3n preparada para el aumento de vol\u00famenes<\/strong><\/h5>\n<p>La operaci\u00f3n en el Skandinavienkai tambi\u00e9n est\u00e1 preparada para un aumento de vol\u00famenes. Se est\u00e1n preparando espacios adicionales para remolques; otros est\u00e1n en camino, ya que el Skandinavienkai se est\u00e1 ampliando. Adem\u00e1s de nuevas \u00e1reas y un nuevo edificio, se est\u00e1 construyendo un acceso adicional a la terminal. Esto ayudar\u00e1 a que los transportes fluyan de manera confiable durante las horas pico.<\/p>\n<p>Paralelamente, la LHG crear\u00e1 el puesto de coordinador ferroviario. Este deber\u00e1 gestionar todos los movimientos ferroviarios en las v\u00edas internas del ferrocarril del puerto, que bajo la direcci\u00f3n de la LHG abarcan un total de 27 kil\u00f3metros. Esto incluye, adem\u00e1s de los trenes intermodales, tambi\u00e9n vagones individuales y trenes completos con productos forestales, acero y autom\u00f3viles.<\/p>\n<p>Proyectos de investigaci\u00f3n como la iniciativa recientemente presentada <em>Baltic Future Port<\/em> tienen como objetivo hacer que el puerto y su conexi\u00f3n con el hinterland sean m\u00e1s eficientes mediante medios digitales. Esto incluye el llamado <em>Traingate<\/em> as\u00ed como la soluci\u00f3n de software interno <em>LHG Rail.<\/em><\/p>\n<h5><strong>Control digital de interfaces<\/strong><\/h5>\n<p>El Traingate tiene como objetivo registrar sistem\u00e1ticamente todas las unidades de carga que llegan al puerto por ferrocarril. Servir\u00e1 para el control digital de interfaces, por ejemplo, para verificar el estado de los vagones y las unidades de carga en el puerto. El software <em>LHG Rail<\/em> asegurar\u00e1 que las capacidades de las v\u00edas se utilicen de manera \u00f3ptima. El objetivo de las medidas ser\u00e1 cargar y descargar trenes en el Skandinavienkai de manera a\u00fan m\u00e1s efectiva y eficiente.<\/p>\n<p>Un papel central en el plan maestro lo desempe\u00f1a la filial de la LHG, European Cargo Logistics (ECL). Esta est\u00e1 ampliando continuamente sus transportes existentes y planea salidas adicionales hacia Duisburgo, Ludwigshafen y Verona. Adem\u00e1s, ECL est\u00e1 trabajando en diversas nuevas conexiones. La empresa est\u00e1 investigando destinos en el \u00e1rea de los puertos del oeste, Luxemburgo, Suiza y Catalu\u00f1a\/Espa\u00f1a. Nordic Rail Services (NRS) tambi\u00e9n est\u00e1 respondiendo al aumento de los transportes. Encargada de parte de las maniobras en la terminal, NRS est\u00e1 aumentando su personal en el turno nocturno, creando as\u00ed m\u00e1s capacidades de maniobra.<\/p>\n<h5><strong>ECL con un nuevo sistema TMS<\/strong><\/h5>\n<p>Para hacer frente a los nuevos requisitos y organizar los transportes a un alto nivel, ECL tambi\u00e9n introducir\u00e1 un nuevo software de gesti\u00f3n de transporte (TMS). Esto permitir\u00e1 a la empresa trabajar de manera m\u00e1s eficiente internamente, y los clientes tambi\u00e9n se beneficiar\u00e1n directamente: el sistema simplifica los procesos de reserva intermodales y mejora el flujo de informaci\u00f3n. Los transportistas podr\u00e1n as\u00ed tener una mejor visi\u00f3n general de sus reservas, rastrear env\u00edos y recibir informaci\u00f3n actualizada sobre el estado.<\/p>\n<p>El director general de la LHG, Sebastian J\u00fcrgens, resume: \u00abNuestra estrategia se basa en varios enfoques: por un lado, queremos utilizar las \u00e1reas existentes de manera a\u00fan m\u00e1s eficiente. Donde sea necesario, aumentamos el personal de los equipos, y con la ayuda de nuestros proyectos de investigaci\u00f3n, digitalizamos nuestros procesos. As\u00ed, estamos sentando las bases para una utilizaci\u00f3n \u00f3ptima de nuestras capacidades.\u00bb<\/p>\n<p>Foto: \u00a9 Michael Imhoff\/LHG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sociedad Portuaria de L\u00fcbeck (LHG) se est\u00e1 preparando para un aumento en los transportes ferroviarios. Por esta raz\u00f3n, la LHG ha elaborado un plan maestro<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-25288","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La Sociedad Portuaria de L\u00fcbeck (LHG) se est\u00e1 preparando para un aumento en los transportes ferroviarios. Por esta raz\u00f3n, la LHG ha elaborado un plan maestro [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-06T16:26:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:01:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal\",\"datePublished\":\"2021-05-06T16:26:51+00:00\",\"dateModified\":\"2025-12-15T12:01:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/\"},\"wordCount\":876,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/\",\"name\":\"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-05-06T16:26:51+00:00\",\"dateModified\":\"2025-12-15T12:01:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/05\\\/06\\\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/","og_locale":"es_ES","og_type":"article","og_title":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24","og_description":"La Sociedad Portuaria de L\u00fcbeck (LHG) se est\u00e1 preparando para un aumento en los transportes ferroviarios. Por esta raz\u00f3n, la LHG ha elaborado un plan maestro [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-06T16:26:51+00:00","article_modified_time":"2025-12-15T12:01:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/"},"author":{"name":"","@id":""},"headline":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal","datePublished":"2021-05-06T16:26:51+00:00","dateModified":"2025-12-15T12:01:37+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/"},"wordCount":876,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/","url":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/","name":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-05-06T16:26:51+00:00","dateModified":"2025-12-15T12:01:37+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/05\/06\/el-puerto-de-lubeck-amplia-capacidades-para-el-transporte-intermodal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"El puerto de L\u00fcbeck ampl\u00eda capacidades para el transporte intermodal"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=25288"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25288\/revisions"}],"predecessor-version":[{"id":46282,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/25288\/revisions\/46282"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=25288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=25288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=25288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}