{"id":24142,"date":"2021-03-22T17:54:27","date_gmt":"2021-03-22T16:54:27","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/"},"modified":"2025-12-15T12:56:19","modified_gmt":"2025-12-15T11:56:19","slug":"dachser-food-une-en-neuss-a-tres-productores-de-alimentos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/","title":{"rendered":"Dachser Food une en Neuss a tres productores de alimentos"},"content":{"rendered":"<p>A trav\u00e9s de una nueva plataforma de frescura con conexi\u00f3n directa a la red, DACHSER Food Logistics acerca y acelera a tres fabricantes de alimentos en Neuss a sus clientes en Alemania y Europa. Los fabricantes de productos l\u00e1cteos Arla y Ornua (\u00abKerrygold<\/p>\n<p>(Kempten\/Neuss) Cuando la vida cotidiana se vuelve agitada, para muchas personas el deporte de resistencia es el medio elegido para despejar la mente y absorber nuevas ideas y una dosis extra de energ\u00eda con el aire fresco. Stefan Behrendt disfruta de montar en su bicicleta de carreras en su escaso tiempo libre. Al mismo tiempo, el gerente general del centro log\u00edstico de DACHSER en Niederrhein ha liderado a su equipo en los \u00faltimos dos a\u00f1os para construir una oferta log\u00edstica universal para los fabricantes de productos frescos en medio de la pandemia de Corona.<\/p>\n<h5><strong>Cadenas log\u00edsticas eficientes y confiables<\/strong><\/h5>\n<p>DACHSER ha invertido alrededor de 2,5 millones de euros en Neuss, cerca de D\u00fcsseldorf, en la remodelaci\u00f3n de un almac\u00e9n con \u00e1reas de almacenamiento refrigeradas para casi 26,000 palets. 80 empleados fueron contratados y capacitados bajo las dif\u00edciles condiciones de la pandemia. Alfred Miller, director general de DACHSER Food Logistics, explica: \u00abAqu\u00ed tenemos condiciones \u00f3ptimas para agrupar grandes vol\u00famenes del almac\u00e9n con las cantidades de los clientes de distribuci\u00f3n de la regi\u00f3n y abastecer la mayor parte de los almacenes centrales de las cadenas de retail alemanas directamente desde la fuente. As\u00ed elevamos la eficiencia de la log\u00edstica alimentaria a un nuevo nivel superior.\u00bb La combinaci\u00f3n de varios factores hace la diferencia decisiva. \u00abProporcionamos cadenas log\u00edsticas muy eficientes y al mismo tiempo confiables, que pueden manejar grandes cantidades y fluctuaciones t\u00edpicas del sector. Y al cargador le quitamos mucho trabajo en el procesamiento de pedidos y servicio. Adem\u00e1s, hay una log\u00edstica de informaci\u00f3n altamente digitalizada que acompa\u00f1a los env\u00edos, todo de una sola mano\u00bb, contin\u00faa Miller.<\/p>\n<h5><strong>De la pr\u00e1ctica para la pr\u00e1ctica<\/strong><\/h5>\n<p>En 2019, el momento fue el adecuado y una idea largamente acariciada pudo ser implementada, informa el gerente general Stefan Behrendt. El centro log\u00edstico de DACHSER en Niederrhein, que se encuentra en medio de una zona metropolitana con m\u00e1s de diez millones de habitantes, recibi\u00f3 m\u00e1s o menos al mismo tiempo solicitudes de tres grandes productores de alimentos para asumir servicios de almacenamiento controlados por temperatura: de los fabricantes de productos l\u00e1cteos Arla, Ornua (conocido por la marca \u00abKerrygold\u00bb) y del productor de jugos frescos Valensina. \u00abOrnua y Valensina ya eran clientes de DACHSER desde hace mucho tiempo en el \u00e1rea de distribuci\u00f3n y buscaban una soluci\u00f3n log\u00edstica integral. El gigante dan\u00e9s de productos l\u00e1cteos Arla, que obtiene productos de sus lecher\u00edas en toda Europa, se uni\u00f3 como nuevo cliente de almac\u00e9n\u00bb, dice Behrendt. \u00abAgrupamos estas solicitudes en un gran proyecto y creamos un concepto que une a las tres empresas bajo un mismo techo.\u00bb La magnitud de los nuevos negocios permite a la sucursal agrupar los vol\u00famenes del almac\u00e9n multiusuario con las cantidades existentes de los clientes de distribuci\u00f3n de la regi\u00f3n para transportes directos al comercio. \u00abAproximadamente el 70 por ciento de todos los almacenes centrales de las cadenas de retail en Alemania, as\u00ed como en los Pa\u00edses Bajos, B\u00e9lgica y Austria, pueden ser abastecidos diariamente de manera directa a trav\u00e9s de esta nueva plataforma de frescura sin necesidad de transbordo adicional\u00bb, explica Behrendt. Con el almacenamiento de sus existencias \u00abcerca de la red\u00bb, los clientes tienen la posibilidad de reaccionar muy r\u00e1pidamente a pedidos a corto plazo, lo que es ideal para los cargadores de productos frescos con una fecha de caducidad corta y requisitos de tiempo de entrega correspondientes.<\/p>\n<h5><strong>Paquete integral convincente<\/strong><\/h5>\n<p>Andy Johnson, director de log\u00edstica en Arla Foods Germany, y Ann-Katrin Gie\u00df del departamento de compras de Arla Foods ven a su empresa con DACHSER como proveedor de sistemas en el \u00e1rea de alimentos perfectamente posicionada. \u00abEl paquete integral ofrecido por DACHSER, que incluye el servicio de almacenamiento en Neuss y la fuerte red de transporte con entregas de alta frecuencia a nuestros clientes comerciales, nos convenci\u00f3 desde el principio.\u00bb Al igual que la forma de trabajo impulsada por IT del proveedor log\u00edstico, que asegura transparencia en la cadena de suministro. \u00abLa digitalizaci\u00f3n de la cadena de suministro ha avanzado en los \u00faltimos a\u00f1os y seguir\u00e1 haci\u00e9ndolo. Aqu\u00ed hay potenciales que deben ser aprovechados\u00bb, est\u00e1 convencido J\u00fcrgen Retzlaff, jefe de log\u00edstica de Ornua Deutschland GmbH. Para \u00e9l, las ventajas de colaborar con DACHSER no solo radican en la flexibilidad respaldada por IT en el manejo de horarios ajustados y la alta volatilidad del mercado, sino tambi\u00e9n en la sostenibilidad ambiental que se deriva de los efectos de agrupamiento en la cadena de suministro. Esto tambi\u00e9n es respaldado por Felix M\u00fcller de la direcci\u00f3n del grupo Valensina: \u00abLa plataforma de log\u00edstica de almacenamiento refrigerado se ha construido sobre un est\u00e1ndar moderno, lo que permite una forma de trabajo efectiva tanto para nosotros como clientes, como para DACHSER en el almac\u00e9n multiusuario. As\u00ed, Valensina pudo mejorar su huella de CO2 en alimentos. Este es un aspecto importante para nuestra empresa.\u00bb<\/p>\n<h5><strong>Expansi\u00f3n en varias fases<\/strong><\/h5>\n<p>La expansi\u00f3n hacia una plataforma regional de agrupamiento para productos frescos se llev\u00f3 a cabo en varias fases. Para ello, se moderniz\u00f3 y actualiz\u00f3 gran parte del almac\u00e9n existente para productos que requieren refrigeraci\u00f3n de 0 a 2 grados y de 2 a 7 grados. La instalaci\u00f3n en funcionamiento y el traslado o la entrada de los tres clientes bajo condiciones de pandemia fue un enorme desaf\u00edo. \u00abPero sab\u00eda en todo momento: \u00a1Lo lograremos! Y lo logramos, incluso est\u00e1bamos por delante del plan del proyecto\u00bb, se alegra Behrendt por el rendimiento del equipo. \u00abDespu\u00e9s de la implementaci\u00f3n viene la optimizaci\u00f3n\u00bb, se\u00f1ala el director de la sucursal. \u00abLa pr\u00f3xima fase de expansi\u00f3n prev\u00e9 8,000 espacios de almacenamiento refrigerados adicionales en 2021.\u00bb Para esto, ya se est\u00e1n llevando a cabo conversaciones con otros interesados en las \u00e1reas de productos l\u00e1cteos, embutidos y alimentos convenientes. Stefan Behrendt y su equipo est\u00e1n ansiosos por ello: \u00abCuanto mayor es el desaf\u00edo, mayor es la diversi\u00f3n\u00bb, dice el entusiasta del deporte con una sonrisa y agrega: \u00abEs muy posible que este a\u00f1o vuelva a recorrer algunos kil\u00f3metros extra en la bicicleta.\u00bb<br \/>Foto: \u00a9 Dachser<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de una nueva plataforma de frescura con conexi\u00f3n directa a la red, DACHSER Food Logistics acerca y acelera a tres fabricantes de alimentos en<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-24142","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachser Food une en Neuss a tres productores de alimentos - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachser Food une en Neuss a tres productores de alimentos - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A trav\u00e9s de una nueva plataforma de frescura con conexi\u00f3n directa a la red, DACHSER Food Logistics acerca y acelera a tres fabricantes de alimentos en [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-22T16:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:56:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dachser Food une en Neuss a tres productores de alimentos\",\"datePublished\":\"2021-03-22T16:54:27+00:00\",\"dateModified\":\"2025-12-15T11:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/\"},\"wordCount\":1111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/\",\"name\":\"Dachser Food une en Neuss a tres productores de alimentos - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-03-22T16:54:27+00:00\",\"dateModified\":\"2025-12-15T11:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/03\\\/22\\\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachser Food une en Neuss a tres productores de alimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachser Food une en Neuss a tres productores de alimentos - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/","og_locale":"es_ES","og_type":"article","og_title":"Dachser Food une en Neuss a tres productores de alimentos - Loginfo24","og_description":"A trav\u00e9s de una nueva plataforma de frescura con conexi\u00f3n directa a la red, DACHSER Food Logistics acerca y acelera a tres fabricantes de alimentos en [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-03-22T16:54:27+00:00","article_modified_time":"2025-12-15T11:56:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/"},"author":{"name":"","@id":""},"headline":"Dachser Food une en Neuss a tres productores de alimentos","datePublished":"2021-03-22T16:54:27+00:00","dateModified":"2025-12-15T11:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/"},"wordCount":1111,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/","url":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/","name":"Dachser Food une en Neuss a tres productores de alimentos - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-03-22T16:54:27+00:00","dateModified":"2025-12-15T11:56:19+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/03\/22\/dachser-food-une-en-neuss-a-tres-productores-de-alimentos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dachser Food une en Neuss a tres productores de alimentos"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/24142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=24142"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/24142\/revisions"}],"predecessor-version":[{"id":44008,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/24142\/revisions\/44008"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=24142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=24142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=24142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}