{"id":23262,"date":"2021-02-11T13:44:35","date_gmt":"2021-02-11T12:44:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/"},"modified":"2025-12-15T12:52:16","modified_gmt":"2025-12-15T11:52:16","slug":"la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/","title":{"rendered":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht"},"content":{"rendered":"<p>El grupo Zeitfracht, el log\u00edstico de Berl\u00edn, es la primera empresa que implementa completamente el nuevo sistema operativo SaaS, sennOS, de sennder para digitalizar todos los procesos de transporte. A trav\u00e9s de sennOS, Zeitfracht gestionar\u00e1 m\u00e1s de 100 millones de kil\u00f3metros de viajes en cami\u00f3n al a\u00f1o; la transparencia y la eficiencia de los viajes de transporte se incrementar\u00e1n.<\/p>\n<p>(Berl\u00edn) sennder, la principal empresa de log\u00edstica digital de Europa, y Zeitfracht, el log\u00edstico de Berl\u00edn, impulsar\u00e1n la digitalizaci\u00f3n del mercado europeo de transporte por carretera mediante una asociaci\u00f3n estrat\u00e9gica. Zeitfracht digitalizar\u00e1 todos los procesos de transporte a trav\u00e9s de la nueva plataforma de Software Como Servicio (SaaS) de sennder, sennOS. Anualmente, m\u00e1s de 100 millones de kil\u00f3metros de viajes de transporte ser\u00e1n gestionados a trav\u00e9s de la plataforma digital de sennder.<\/p>\n<p><strong>Visibilidad GPS completa de todos los veh\u00edculos<\/strong><\/p>\n<p>Zeitfracht es el primer socio estrat\u00e9gico de la plataforma SaaS de sennder, sennOS, que implementar\u00e1 completamente para la gesti\u00f3n del transporte. La soluci\u00f3n digital permite a Zeitfracht navegar de la manera m\u00e1s eficiente posible una flota de 300 camiones y 800 plataformas intercambiables. Zeitfracht se beneficia de la visibilidad GPS completa de todos los camiones y de la optimizaci\u00f3n de rutas a trav\u00e9s del algoritmo desarrollado por sennder.<\/p>\n<p>Zeitfracht y sennder se comprometen a preparar la industria log\u00edstica para un futuro sostenible; mediante el uso de datos para optimizar la eficiencia de las rutas, sennOS reduce la cantidad de viajes vac\u00edos, disminuye el impacto ambiental del transporte por carretera y al mismo tiempo reduce los costos de transporte.<\/p>\n<p>Zeitfracht es considerado un pionero en el sector de servicios log\u00edsticos; la asociaci\u00f3n acelerar\u00e1 la digitalizaci\u00f3n de los transportes de Zeitfracht. Adem\u00e1s de aumentar la eficiencia del transporte y la visibilidad de todos los camiones, sennOS conecta a los cargadores comerciales directamente con los transportistas, ofreciendo as\u00ed una interfaz digital para la facturaci\u00f3n, la planificaci\u00f3n y la reserva de viajes. La digitalizaci\u00f3n y automatizaci\u00f3n de los procesos diarios crea eficiencias operativas en todo el ecosistema de transporte.<\/p>\n<h5><strong>Financiaci\u00f3n para el crecimiento y desarrollo<\/strong><\/h5>\n<p>Recientemente, sennder anunci\u00f3 una financiaci\u00f3n de Serie D de 160 millones de d\u00f3lares para la digitalizaci\u00f3n de la industria log\u00edstica europea. La mayor parte de la financiaci\u00f3n se destinar\u00e1 al crecimiento y desarrollo de la tecnolog\u00eda de sennder y a impulsar la r\u00e1pida expansi\u00f3n en nuevos mercados europeos con un enfoque en asociaciones estrat\u00e9gicas. La asociaci\u00f3n con Zeitfracht demuestra las sinergias y oportunidades sin precedentes que surgen para Zeitfracht y sennder al conectar la industria log\u00edstica con la tecnolog\u00eda m\u00e1s avanzada. La empresa de log\u00edstica digital sennder, que ahora est\u00e1 presente en 14 mercados, considera esto como clave para su crecimiento.<\/p>\n<p>David Nothacker, CEO y cofundador de sennder, dice: \u201cEstamos emocionados de trabajar con Zeitfracht, otro pionero en la industria log\u00edstica. Zeitfracht digitalizar\u00e1 todas sus cargas de transporte a trav\u00e9s de nuestro sennOS. Al elegir nuestra tecnolog\u00eda para la gesti\u00f3n de flotas de camiones, Zeitfracht env\u00eda una fuerte se\u00f1al en la industria log\u00edstica sobre las soluciones digitales de sennder. Nuestra creciente oferta SaaS seguir\u00e1 fortaleciendo nuestra posici\u00f3n como el principal transportista digital de Europa. Nuestra misi\u00f3n es preparar la industria log\u00edstica para el futuro. M\u00e1s de 100 millones de d\u00f3lares de nuestra financiaci\u00f3n de Serie D se destinar\u00e1n al desarrollo y expansi\u00f3n de nuestra tecnolog\u00eda desarrollada internamente. Zeitfracht se beneficiar\u00e1 directamente de esto.\u00bb<\/p>\n<h5><strong>Digitalizaci\u00f3n a un nuevo nivel<\/strong><\/h5>\n<p>sennder se basa en asociaciones estrat\u00e9gicas para seguir revolucionando el transporte de mercanc\u00edas en Europa. Junto con Scania, Siemens y Poste Italiane, sennder ya ha creado sinergias y proporciona servicios de transporte para 10 de las empresas que figuran en el DAX 30 alem\u00e1n y 11 en el EuroStoxx 50.<\/p>\n<p>Dominik Wiehage, CEO de Zeitfracht, a\u00f1ade: \u00abEstamos seguros de que la conexi\u00f3n completa con la plataforma digital sennOS de sennder llevar\u00e1 nuestra digitalizaci\u00f3n a un nuevo nivel. La colaboraci\u00f3n con sennder nos permite revolucionar toda nuestra cadena de procesos. Estamos creando un canal de ventas que nos posiciona \u00f3ptimamente para el futuro. Estamos ansiosos por colaborar con el experimentado y din\u00e1mico equipo de sennder.\u00bb<\/p>\n<h5><strong>Sobre sennder<\/strong><\/h5>\n<p>sennder fue fundada en 2015 por David Nothacker, Julius K\u00f6hler y Nicolaus Schefenacker y hoy es el principal transportista digital europeo, que ofrece a los cargadores comerciales acceso a nuestra flota conectada de miles de camiones. En una industria tradicional, sennder se mueve r\u00e1pidamente y se centra en la digitalizaci\u00f3n y automatizaci\u00f3n de todos los procesos en la log\u00edstica por carretera. Con un equipo de m\u00e1s de 800 empleados, sennder gestiona m\u00e1s de 10,000 camiones en toda Europa. A trav\u00e9s del uso de su tecnolog\u00eda propia, sennder est\u00e1 construyendo un ecosistema que lleva a la industria a un nuevo nivel de transparencia, eficiencia y flexibilidad en el siglo XXI. sennder cuenta con el apoyo de destacados inversores europeos.<\/p>\n<h5><strong>Sobre Zeitfracht<\/strong><\/h5>\n<p>KNV Zeitfracht es el principal proveedor de servicios log\u00edsticos para la industria del libro y los medios. Forma parte del grupo Zeitfracht, una empresa familiar con sede en Berl\u00edn. KNV Zeitfracht emplea a alrededor de 1,600 personas en las ubicaciones de Erfurt y Stuttgart. El centro log\u00edstico de KNV Zeitfracht en Erfurt es uno de los m\u00e1s grandes y modernos de Europa en log\u00edstica de medios.<\/p>\n<p>Gr\u00e1fico: \u00a9 sennder<\/p>\n<p><a href=\"https:\/\/www.zeitfracht-gruppe.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.zeitfracht-gruppe.de<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.sennder.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.sennder.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo Zeitfracht, el log\u00edstico de Berl\u00edn, es la primera empresa que implementa completamente el nuevo sistema operativo SaaS, sennOS, de sennder para digitalizar todos los<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-23262","post","type-post","status-publish","format-standard","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El grupo Zeitfracht, el log\u00edstico de Berl\u00edn, es la primera empresa que implementa completamente el nuevo sistema operativo SaaS, sennOS, de sennder para digitalizar todos los [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-11T12:44:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:52:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht\",\"datePublished\":\"2021-02-11T12:44:35+00:00\",\"dateModified\":\"2025-12-15T11:52:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/\"},\"wordCount\":961,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/\",\"name\":\"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2021-02-11T12:44:35+00:00\",\"dateModified\":\"2025-12-15T11:52:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/02\\\/11\\\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/","og_locale":"es_ES","og_type":"article","og_title":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24","og_description":"El grupo Zeitfracht, el log\u00edstico de Berl\u00edn, es la primera empresa que implementa completamente el nuevo sistema operativo SaaS, sennOS, de sennder para digitalizar todos los [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-02-11T12:44:35+00:00","article_modified_time":"2025-12-15T11:52:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/"},"author":{"name":"","@id":""},"headline":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht","datePublished":"2021-02-11T12:44:35+00:00","dateModified":"2025-12-15T11:52:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/"},"wordCount":961,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/","url":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/","name":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2021-02-11T12:44:35+00:00","dateModified":"2025-12-15T11:52:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/02\/11\/la-digitalizacion-de-la-logistica-sennder-otorga-licencia-para-su-plataforma-saas-a-zeitfracht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"La digitalizaci\u00f3n de la log\u00edstica: sennder otorga licencia para su plataforma SaaS a Zeitfracht"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/23262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=23262"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/23262\/revisions"}],"predecessor-version":[{"id":42250,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/23262\/revisions\/42250"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=23262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=23262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=23262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}