{"id":22818,"date":"2021-01-25T19:15:34","date_gmt":"2021-01-25T18:15:34","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/"},"modified":"2021-01-25T19:15:34","modified_gmt":"2021-01-25T18:15:34","slug":"daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/","title":{"rendered":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz"},"content":{"rendered":"<p><strong>Daimler India Commercial Vehicles (DICV) ha presentado el BharatBenz &#8216;BSafe Express&#8217;. Se trata de un cami\u00f3n frigor\u00edfico especial que es adecuado para el transporte seguro de vacunas contra el COVID-19. Equipado con conectividad de \u00faltima generaci\u00f3n, el BSafe Express utiliza unidades de refrigeraci\u00f3n reci\u00e9n desarrolladas que garantizan que la temperatura y la estabilidad de las vacunas se supervisen y mantengan con precisi\u00f3n en todas las fases de la entrega. La base de la unidad de refrigeraci\u00f3n es el chasis de cami\u00f3n pesado BharatBenz 2823R.<\/strong><\/p>\n<p>(Chennai\/Stuttgart) En el estreno del cami\u00f3n en la capital india, Nueva Delhi, Satyakam Arya, Director General y CEO de Daimler India Commercial Vehicles, dijo: \u00abLa combinaci\u00f3n de un chasis fuerte y confiable con una unidad de refrigeraci\u00f3n ligera y aislada t\u00e9rmicamente, junto con una soluci\u00f3n de conectividad de vanguardia, convierte al &#8216;BSafe Express&#8217; de BharatBenz en la soluci\u00f3n perfecta para el desaf\u00edo de la infraestructura de la cadena de fr\u00edo en India. Con este cami\u00f3n, podemos entregar vacunas en perfecto estado incluso a los lugares m\u00e1s remotos, brindando as\u00ed esperanza a m\u00e1s de 1.3 mil millones de personas para un regreso a la normalidad.\u00bb<\/p>\n<h5><strong>Transporte r\u00e1pido y seguro de vacunas en toda India<\/strong><\/h5>\n<p>India ha lanzado recientemente su campa\u00f1a de vacunaci\u00f3n contra el coronavirus, con el objetivo de vacunar a 300 millones de personas para julio de 2021. El BharatBenz BSafe Express ofrece a las empresas de log\u00edstica indias una soluci\u00f3n para contribuir al objetivo del pa\u00eds de controlar el COVID lo m\u00e1s r\u00e1pido posible. Un enorme desaf\u00edo en un pa\u00eds con la segunda poblaci\u00f3n m\u00e1s grande del mundo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8699\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21_1.jpg\" alt=\"\" width=\"1024\" height=\"543\" \/><\/p>\n<p>El contenedor frigor\u00edfico proviene del proveedor de autom\u00f3viles Motherson Group. Est\u00e1 fabricado con pl\u00e1stico reforzado con fibra de vidrio, espuma XPS y otros materiales cuidadosamente seleccionados que garantizan que la estructura sea estable, impermeable y resistente a la corrosi\u00f3n, y al mismo tiempo tenga un peso ligero y un alto aislamiento t\u00e9rmico. El contenedor se puede ensamblar en el lugar en solo 96 horas, lo que lo convierte en una soluci\u00f3n mucho m\u00e1s pr\u00e1ctica que los productos convencionales, cuya entrega puede tardar tres semanas o m\u00e1s.<\/p>\n<h5><strong>Sensores IoT para monitorear la temperatura<\/strong><\/h5>\n<p>Con sensores IoT personalizados integrados en el contenedor, los gerentes de flota pueden monitorear la temperatura, la humedad, los golpes, la inclinaci\u00f3n y los da\u00f1os. Tambi\u00e9n pueden ajustar la temperatura seg\u00fan sea necesario y activar una alarma en caso de problemas. Esta tecnolog\u00eda de sensores tambi\u00e9n est\u00e1 integrada con el seguimiento de todos los inventarios a bordo mediante c\u00f3digo QR, lo que permite a los usuarios verificar la ubicaci\u00f3n, el estado y el historial de cada paquete. Combinado con la plataforma de telem\u00e1tica &#8216;Truckonnect&#8217; de BharatBenz, el BSafe Express ofrece a los distribuidores de vacunas una seguridad absoluta mediante el seguimiento en tiempo real del veh\u00edculo y su valiosa carga.<\/p>\n<p>Fotos: \u00a9 Daimler Truck<\/p>\n<p><a href=\"https:\/\/www.daimler-truck.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.daimler-truck.com<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"https:\/\/daimler-trucksasia.in\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/daimler-trucksasia.in<\/a>\u00a0\u00a0\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.bharatbenz.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.bharatbenz.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daimler India Commercial Vehicles (DICV) ha presentado el BharatBenz &#8216;BSafe Express&#8217;. Se trata de un cami\u00f3n frigor\u00edfico especial que es adecuado para el transporte seguro de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":14625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-22818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Daimler India Commercial Vehicles (DICV) ha presentado el BharatBenz &#8216;BSafe Express&#8217;. Se trata de un cami\u00f3n frigor\u00edfico especial que es adecuado para el transporte seguro de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-25T18:15:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1198\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz\",\"datePublished\":\"2021-01-25T18:15:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_25.1.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/\",\"name\":\"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_25.1.21.jpg\",\"datePublished\":\"2021-01-25T18:15:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_25.1.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Daimler_25.1.21.jpg\",\"width\":1198,\"height\":653},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2021\\\/01\\\/25\\\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/","og_locale":"es_ES","og_type":"article","og_title":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24","og_description":"Daimler India Commercial Vehicles (DICV) ha presentado el BharatBenz &#8216;BSafe Express&#8217;. Se trata de un cami\u00f3n frigor\u00edfico especial que es adecuado para el transporte seguro de [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-01-25T18:15:34+00:00","og_image":[{"width":1198,"height":653,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/"},"author":{"name":"","@id":""},"headline":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz","datePublished":"2021-01-25T18:15:34+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/","url":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/","name":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg","datePublished":"2021-01-25T18:15:34+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Daimler_25.1.21.jpg","width":1198,"height":653},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2021\/01\/25\/daimler-trucks-presenta-camiones-frigorificos-de-bharatbenz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Daimler Trucks presenta camiones frigor\u00edficos de BharatBenz"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/22818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=22818"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/22818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media\/14625"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=22818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=22818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=22818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}