{"id":21866,"date":"2020-12-03T19:51:44","date_gmt":"2020-12-03T18:51:44","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/"},"modified":"2025-12-15T12:46:02","modified_gmt":"2025-12-15T11:46:02","slug":"hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/","title":{"rendered":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen"},"content":{"rendered":"<p>Con 38,000 m2, el nuevo centro log\u00edstico en Chempark en Dormagen es uno de los proyectos de cadena de suministro m\u00e1s grandes y complejos que Hoyer ha gestionado desde cero. En el verano de 2020, las instalaciones en el terreno previamente vac\u00edo se pusieron en funcionamiento de manera escalonada tras un per\u00edodo de construcci\u00f3n de aproximadamente dos a\u00f1os. Alrededor de 20 empleados en cinco operaciones ahora aseguran procesos sin problemas a lo largo de la cadena de suministro.<\/p>\n<p>(Hamburgo) Con la nueva construcci\u00f3n del centro log\u00edstico, Hoyer demuestra su competencia en el desarrollo de soluciones integrales de cadena de suministro en la log\u00edstica por contrato. La comprensi\u00f3n de los detalles y una amplia experiencia en los procesos dentro de los flujos operativos del cliente son la clave. \u00abEl centro log\u00edstico est\u00e1 completamente construido y estructurado seg\u00fan las necesidades diferenciadas de los clientes\u00bb, dice Ulrich Gr\u00e4tz, Director Global de Soluciones de Cadena de Suministro (SCS) en el Grupo Hoyer,<\/p>\n<h5><strong>An\u00e1lisis exhaustivos<\/strong><\/h5>\n<p> \u00abAn\u00e1lisis exhaustivos, asesor\u00edas y una gesti\u00f3n de proyectos bien coordinada fueron la base. A pesar de peque\u00f1os retrasos debido a los efectos de la pandemia de Covid-19, estamos muy satisfechos\u00bb, explica Gr\u00e4tz. Hoyer invirti\u00f3 alrededor de 25 millones de EUR en el centro log\u00edstico, que fue pr\u00e1cticamente terminado en junio de 2020 tras dos a\u00f1os de construcci\u00f3n. Alrededor de 20 empleados operan en el sitio con equipos de \u00faltima generaci\u00f3n, como una planta de llenado adaptada a las necesidades del cliente. Adem\u00e1s, se utiliza un software de gesti\u00f3n de inventario especialmente desarrollado. El complejo consta de cinco \u00e1reas principales. Una bodega con espacios para 10,000 cajas de metal, llenas de caucho sint\u00e9tico, es una de estas \u00e1reas. Esta es transportada exclusivamente por el Grupo Hoyer para un cliente desde su planta en Chempark hasta la bodega. Aqu\u00ed, los empleados se encargan de almacenar y retirar las cajas, prepararlas para el env\u00edo y cargarlas en camiones.<\/p>\n<h5><strong>12,000 espacios para palets<\/strong><\/h5>\n<p> En la segunda \u00e1rea, el almac\u00e9n de palets, hay 12,000 espacios de almacenamiento en estanter\u00edas altas para diversas materias primas y productos terminados. \u00abNuestros servicios para el cliente incluyen todos los servicios relacionados con el almacenamiento, como la recepci\u00f3n, almacenamiento y retirada de mercanc\u00edas en palets\u00bb, dice Gr\u00e4tz. Adyacente al almac\u00e9n de palets se encuentra el almac\u00e9n de materiales de embalaje, que cuenta con m\u00e1s de 3,000 espacios de almacenamiento. Hoyer se encarga de una serie de procesos log\u00edsticos como la recepci\u00f3n y almacenamiento de materiales de embalaje, la retirada y carga. Tambi\u00e9n se incluyen en el paquete de servicios el etiquetado y el control de materiales de embalaje, as\u00ed como diversas actividades especiales a petici\u00f3n. Los servicios se complementan con el llenado y almacenamiento de dispersiones de poliuretano. Dos plantas de llenado est\u00e1n disponibles para este prop\u00f3sito en esta \u00e1rea del centro log\u00edstico. El equipo de Hoyer planifica y realiza transportes desde la producci\u00f3n hasta el centro log\u00edstico y llena las dispersiones en barriles y grandes contenedores. \u00abAdem\u00e1s, nos encargamos del almacenamiento y manejo de los envases llenos, la preparaci\u00f3n para el env\u00edo, la selecci\u00f3n, la carga y el env\u00edo\u00bb, a\u00f1ade Ulrich Gr\u00e4tz.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7598 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg\" alt=\"Hoyer; log\u00edstica qu\u00edmica; transporte combinado; intralog\u00edstica; log\u00edstica de almacenamiento\" width=\"1002\" height=\"563\" \/>Dos a\u00f1os de construcci\u00f3n<\/strong><\/h5>\n<p> La duraci\u00f3n de la construcci\u00f3n de todo el centro log\u00edstico fue de aproximadamente dos a\u00f1os. \u00abCon la implementaci\u00f3n de este gran proyecto, hemos fortalecido a\u00fan m\u00e1s nuestro nombre como especialistas en servicios log\u00edsticos a lo largo de toda la cadena de suministro de nuestros clientes\u00bb, enfatiza Ulrich Gr\u00e4tz. \u00abTambi\u00e9n para el futuro, nos hemos propuesto: ofrecer soluciones y establecer est\u00e1ndares en el mercado.\u00bb Las soluciones log\u00edsticas de Supply Chain Solutions se utilizan en todo el mundo. Las actividades clave del \u00e1rea incluyen todos los procesos log\u00edsticos en la planta del cliente y fuera de ella, incluyendo log\u00edstica de planta, llenado y mezcla, operaci\u00f3n de terminales intermodales, terminales de materiales peligrosos y log\u00edstica de granel seco. Actualmente, el Grupo Hoyer est\u00e1 presente en m\u00e1s de 30 operaciones diferentes de productores qu\u00edmicos internacionales, incluyendo varios sitios en Alemania, China y Arabia Saudita. El operador log\u00edstico act\u00faa donde existe demanda por parte de la industria qu\u00edmica de soluciones log\u00edsticas a medida, con calidad confiable y los m\u00e1s altos est\u00e1ndares de seguridad.<\/p>\n<h5><strong>SOBRE Hoyer Group<\/strong><\/h5>\n<p> Hoyer es desde 1946 una de las principales empresas familiares independientes en log\u00edstica de granel a nivel mundial y, como especialista, cuenta con un amplio conocimiento en servicios complejos y una cercan\u00eda especial al cliente. En la log\u00edstica de granel europea y mundial, se desarrollan y realizan soluciones integrales, especialmente para las industrias qu\u00edmica, alimentaria, de gas y de petr\u00f3leo mineral. Alrededor de 6,100 empleados en m\u00e1s de 115 pa\u00edses apoyan a los clientes para tener a\u00fan m\u00e1s \u00e9xito en sus respectivos mercados con soluciones log\u00edsticas bien pensadas. Hoyer cuenta con aproximadamente 2,200 tractores, 2,400 remolques cisterna, 50,100 IBC, 40,800 contenedores cisterna y numerosas instalaciones log\u00edsticas con dep\u00f3sitos, instalaciones de limpieza y talleres. Foto: \u00a9 Hoyer Group <a href=\"https:\/\/www.hoyer-group.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.hoyer-group.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con 38,000 m2, el nuevo centro log\u00edstico en Chempark en Dormagen es uno de los proyectos de cadena de suministro m\u00e1s grandes y complejos que Hoyer<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-21866","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Con 38,000 m2, el nuevo centro log\u00edstico en Chempark en Dormagen es uno de los proyectos de cadena de suministro m\u00e1s grandes y complejos que Hoyer [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T18:51:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:46:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen\",\"datePublished\":\"2020-12-03T18:51:44+00:00\",\"dateModified\":\"2025-12-15T11:46:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/\"},\"wordCount\":890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hoyer_3.12.20.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/\",\"name\":\"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hoyer_3.12.20.jpg\",\"datePublished\":\"2020-12-03T18:51:44+00:00\",\"dateModified\":\"2025-12-15T11:46:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hoyer_3.12.20.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hoyer_3.12.20.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/12\\\/03\\\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/","og_locale":"es_ES","og_type":"article","og_title":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24","og_description":"Con 38,000 m2, el nuevo centro log\u00edstico en Chempark en Dormagen es uno de los proyectos de cadena de suministro m\u00e1s grandes y complejos que Hoyer [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-12-03T18:51:44+00:00","article_modified_time":"2025-12-15T11:46:02+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/"},"author":{"name":"","@id":""},"headline":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen","datePublished":"2020-12-03T18:51:44+00:00","dateModified":"2025-12-15T11:46:02+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/"},"wordCount":890,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/","url":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/","name":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg","datePublished":"2020-12-03T18:51:44+00:00","dateModified":"2025-12-15T11:46:02+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hoyer_3.12.20.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2020\/12\/03\/hoyer-pone-en-funcionamiento-el-centro-logistico-en-chempark-dormagen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Hoyer pone en funcionamiento el centro log\u00edstico en Chempark Dormagen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=21866"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21866\/revisions"}],"predecessor-version":[{"id":39924,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21866\/revisions\/39924"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=21866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=21866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=21866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}