{"id":21686,"date":"2020-11-30T18:44:37","date_gmt":"2020-11-30T17:44:37","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/"},"modified":"2025-12-15T12:45:13","modified_gmt":"2025-12-15T11:45:13","slug":"peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/","title":{"rendered":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania"},"content":{"rendered":"<p>A partir del 1 de diciembre de 2020, Peter Str\u00f6m asumir\u00e1 la direcci\u00f3n de Volvo Trucks en Alemania. Sucede a Christian Coolsaet, quien desde el 1 de septiembre es el director general de Volvo Trucks UK &amp; Ireland. Str\u00f6m proviene de PEMA, donde tambi\u00e9n fue director general para Alemania y al mismo tiempo fue Vicepresidente de la Regi\u00f3n Central de TIP.<\/p>\n<p>(Ismaning) Peter Str\u00f6m proviene de PEMA GmbH, donde fue director general en Alemania y Vicepresidente de la Regi\u00f3n Central de TIP. El sueco de nacimiento aporta una amplia experiencia en gesti\u00f3n. Ha ocupado funciones directivas en ventas y marketing en Mercedes-Benz Financial Services y fue director general de Mercedes-Benz CharterWay. Tambi\u00e9n fue Director Comercial Europeo en GE Commercial Finance.<\/p>\n<h5><strong>Alemania es el mercado m\u00e1s competitivo<\/strong><\/h5>\n<p>\u00abComo sueco, asumir la direcci\u00f3n de Volvo Trucks en mi pa\u00eds de elecci\u00f3n, Alemania, me enorgullece. Alemania es el mercado m\u00e1s competitivo de Europa. Poder participar activamente aqu\u00ed es un desaf\u00edo que acepto con gusto. Con los nuevos veh\u00edculos recientemente presentados y un equipo que ya ha tenido \u00e9xito, llevaremos a Volvo Trucks a\u00fan m\u00e1s lejos\u00bb, est\u00e1 seguro Peter Str\u00f6m. Peter Str\u00f6m ha mantenido durante mucho tiempo una buena relaci\u00f3n comercial con Volvo Trucks, ya que PEMA GmbH, como una de las principales empresas de alquiler independientes de veh\u00edculos comerciales pesados en Europa, tambi\u00e9n cuenta con numerosos camiones Volvo en su flota de 20,000 unidades.<\/p>\n<h5><strong>15 a\u00f1os en la industria de veh\u00edculos comerciales<\/strong><\/h5>\n<p>Peter Str\u00f6m naci\u00f3 en 1963 en Suecia y tiene un t\u00edtulo en Derecho y Administraci\u00f3n de Empresas. Desde el a\u00f1o 2000 vive en Alemania y ha trabajado durante 15 a\u00f1os en la industria de veh\u00edculos comerciales en Alemania y Europa. Sucede a Christian Coolsaet, quien desde el 1 de septiembre es el director general de Volvo Trucks UK &amp; Ireland. Peter Str\u00f6m formar\u00e1 parte del equipo de gesti\u00f3n para Europa del Norte y Central y reportar\u00e1 a Anna M\u00fcller, SVP de Volvo Trucks Europa del Norte y Central. Hasta la llegada de Peter Str\u00f6m, Charlotte Olofsson, Directora Financiera de Volvo Trucks en Alemania, dirigi\u00f3 los negocios de forma interina. Foto: \u00a9 Volvo Trucks <a href=\"https:\/\/www.volvotrucks.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.volvotrucks.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 1 de diciembre de 2020, Peter Str\u00f6m asumir\u00e1 la direcci\u00f3n de Volvo Trucks en Alemania. Sucede a Christian Coolsaet, quien desde el 1<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-21686","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A partir del 1 de diciembre de 2020, Peter Str\u00f6m asumir\u00e1 la direcci\u00f3n de Volvo Trucks en Alemania. Sucede a Christian Coolsaet, quien desde el 1 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-30T17:44:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:45:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania\",\"datePublished\":\"2020-11-30T17:44:37+00:00\",\"dateModified\":\"2025-12-15T11:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/\",\"name\":\"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2020-11-30T17:44:37+00:00\",\"dateModified\":\"2025-12-15T11:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/11\\\/30\\\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/","og_locale":"es_ES","og_type":"article","og_title":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24","og_description":"A partir del 1 de diciembre de 2020, Peter Str\u00f6m asumir\u00e1 la direcci\u00f3n de Volvo Trucks en Alemania. Sucede a Christian Coolsaet, quien desde el 1 [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-11-30T17:44:37+00:00","article_modified_time":"2025-12-15T11:45:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/"},"author":{"name":"","@id":""},"headline":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania","datePublished":"2020-11-30T17:44:37+00:00","dateModified":"2025-12-15T11:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/","url":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/","name":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2020-11-30T17:44:37+00:00","dateModified":"2025-12-15T11:45:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2020\/11\/30\/peter-strom-sera-el-nuevo-director-general-de-volvo-trucks-alemania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Peter Str\u00f6m ser\u00e1 el nuevo director general de Volvo Trucks Alemania"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=21686"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21686\/revisions"}],"predecessor-version":[{"id":39566,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/21686\/revisions\/39566"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=21686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=21686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=21686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}