{"id":18967,"date":"2020-08-05T07:00:34","date_gmt":"2020-08-05T05:00:34","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/"},"modified":"2025-12-15T12:33:27","modified_gmt":"2025-12-15T11:33:27","slug":"fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/","title":{"rendered":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich"},"content":{"rendered":"<p>El proveedor de servicios log\u00edsticos Fiege est\u00e1 construyendo un nuevo centro log\u00edstico en Z\u00fclpich, Renania del Norte-Westfalia. Con una ceremonia de colocaci\u00f3n de la primera piedra, se celebr\u00f3 el inicio de las obras. La superficie log\u00edstica de 54,000 m2 se espera que est\u00e9 en funcionamiento en el verano de 2021. La suma de la inversi\u00f3n asciende a 50 millones de euros. La propiedad est\u00e1 destinada al sector de salud de Fiege.<\/p>\n<p>Z\u00fclpich, 03.08.2020. La empresa Fiege est\u00e1 construyendo un nuevo centro log\u00edstico en Z\u00fclpich, Renania del Norte-Westfalia. Situado en el tri\u00e1ngulo urbano de Colonia-Bonn-Aquisgr\u00e1n, se est\u00e1 creando un centro multiusuario con 54,000 metros cuadrados de superficie log\u00edstica, que consta de espacio de almac\u00e9n, oficinas y \u00e1reas sociales. El 3 de agosto de 2020, Fiege celebr\u00f3 el inicio de la construcci\u00f3n en presencia del Ministro de Transporte de NRW, Hendrik W\u00fcst, el alcalde del distrito, G\u00fcnter Rosenke, el alcalde Ulf H\u00fcrtgen y otros representantes de la ciudad de Z\u00fclpich, del inversor LIP Invest, de la oficina de arquitectura J\u00fcrgen Schlake y del contratista general Goldbeck International. Se espera que la propiedad log\u00edstica est\u00e9 terminada en el verano de 2021. Fiege operar\u00e1 la instalaci\u00f3n para varios clientes. La suma de la inversi\u00f3n para el proyecto de nueva construcci\u00f3n es de aproximadamente 50 millones de euros.<\/p>\n<h5>Entrega de instituciones de salud en toda Europa<\/h5>\n<p>\u00abLa construcci\u00f3n se completar\u00e1 en menos de un a\u00f1o. Entonces, Z\u00fclpich ser\u00e1 una nueva y importante sucursal para nuestro creciente sector de salud\u00bb, dice Jan Fiege, Director General de Bienes Ra\u00edces. \u00abLa propiedad en Z\u00fclpich se ajusta muy bien a nuestro perfil de requisitos. Est\u00e1 bien ubicada, cerca de las autopistas A1 y A61.\u00bb Desde Z\u00fclpich, Fiege suministrar\u00e1 a instituciones de salud en toda Europa, como hospitales o distribuidores especializados en productos m\u00e9dicos, con productos de varios clientes del sector farmac\u00e9utico. Para la realizaci\u00f3n de la primera fase de construcci\u00f3n, Fiege ha adquirido una superficie comercial de 100,000 metros cuadrados en el \u00e1rea industrial de Z\u00fclpich \u00abAn der R\u00f6merallee\u00bb.<\/p>\n<h5><strong>Al menos 250 puestos de trabajo<\/strong><\/h5>\n<p>\u00abEstamos contentos de que la empresa Fiege, uno de los principales proveedores de log\u00edstica europeos, se establezca en Z\u00fclpich con este gran proyecto intensivo en mano de obra, que la pol\u00edtica de Z\u00fclpich ya aprob\u00f3 un\u00e1nimemente en la reuni\u00f3n del consejo el 28 de noviembre de 2019\u00bb, enfatiza el alcalde Ulf H\u00fcrtgen. \u00abTambi\u00e9n es alentador que la empresa haya reconocido las oportunidades existentes para m\u00e1s actividades log\u00edsticas en la ubicaci\u00f3n econ\u00f3mica de Z\u00fclpich y que con el proyecto de asentamiento de la empresa Fiege se haya encontrado un reemplazo m\u00e1s que adecuado para la construcci\u00f3n originalmente planificada de un almac\u00e9n de comercio electr\u00f3nico en la superficie\u00bb, contin\u00faa H\u00fcrtgen. La simb\u00f3lica primera pala marca el inicio de un proyecto de asentamiento que crear\u00e1 al menos 250 puestos de trabajo a tiempo completo en la primera fase de construcci\u00f3n en Z\u00fclpich. La opci\u00f3n otorgada a la empresa Fiege para adquirir una superficie comercial adicional adyacente abre a la ubicaci\u00f3n de Z\u00fclpich la perspectiva de que el n\u00famero de puestos de trabajo aumente en los pr\u00f3ximos a\u00f1os a m\u00e1s de 500 en total. Foto: \u00a9 Fiege <a href=\"https:\/\/www.fiege.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.fiege.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proveedor de servicios log\u00edsticos Fiege est\u00e1 construyendo un nuevo centro log\u00edstico en Z\u00fclpich, Renania del Norte-Westfalia. Con una ceremonia de colocaci\u00f3n de la primera piedra,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-18967","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El proveedor de servicios log\u00edsticos Fiege est\u00e1 construyendo un nuevo centro log\u00edstico en Z\u00fclpich, Renania del Norte-Westfalia. Con una ceremonia de colocaci\u00f3n de la primera piedra, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-05T05:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:33:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich\",\"datePublished\":\"2020-08-05T05:00:34+00:00\",\"dateModified\":\"2025-12-15T11:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/\"},\"wordCount\":584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/\",\"name\":\"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2020-08-05T05:00:34+00:00\",\"dateModified\":\"2025-12-15T11:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/08\\\/05\\\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/","og_locale":"es_ES","og_type":"article","og_title":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24","og_description":"El proveedor de servicios log\u00edsticos Fiege est\u00e1 construyendo un nuevo centro log\u00edstico en Z\u00fclpich, Renania del Norte-Westfalia. Con una ceremonia de colocaci\u00f3n de la primera piedra, [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-08-05T05:00:34+00:00","article_modified_time":"2025-12-15T11:33:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/"},"author":{"name":"","@id":""},"headline":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich","datePublished":"2020-08-05T05:00:34+00:00","dateModified":"2025-12-15T11:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/"},"wordCount":584,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/","url":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/","name":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2020-08-05T05:00:34+00:00","dateModified":"2025-12-15T11:33:27+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2020\/08\/05\/fiege-con-la-primera-pala-para-un-nuevo-centro-logistico-en-zulpich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Fiege con la primera pala para un nuevo centro log\u00edstico en Z\u00fclpich"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/18967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=18967"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/18967\/revisions"}],"predecessor-version":[{"id":34233,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/18967\/revisions\/34233"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=18967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=18967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=18967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}