{"id":17709,"date":"2020-05-29T10:32:51","date_gmt":"2020-05-29T08:32:51","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/"},"modified":"2025-12-15T12:28:17","modified_gmt":"2025-12-15T11:28:17","slug":"schneider-y-nova-traffic-van-juntos-hacia-el-futuro","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/","title":{"rendered":"Schneider y Nova Traffic van juntos hacia el futuro"},"content":{"rendered":"<p>El proveedor de servicios log\u00edsticos Schneider &amp; Cie. AG con sede en Basilea adquiere el 100 % de las acciones de Nova Traffic AG con sede en Kloten. La adquisici\u00f3n se realiz\u00f3 en el marco de una planificaci\u00f3n de sucesi\u00f3n. El proveedor de servicios financieros Invision, que participa en Schneider, apoy\u00f3 la transacci\u00f3n.<\/p>\n<p>(Basilea\/Kloten) El grupo Schneider, una participaci\u00f3n de Invision y un proveedor l\u00edder de servicios de transporte en Suiza, se expande mediante la adquisici\u00f3n de la empresa log\u00edstica NOVA TRAFFIC con ubicaciones en Kloten y Embrach. En el marco de la planificaci\u00f3n anticipada de la sucesi\u00f3n de NOVA TRAFFIC, surgi\u00f3 la decisi\u00f3n conjunta de ambos grupos empresariales de unirse, ya que las dos empresas tambi\u00e9n se complementan \u00f3ptimamente en su cartera de productos. Invision ha apoyado al grupo Schneider en esta transacci\u00f3n.<\/p>\n<p>Los empleados, clientes y socios de NOVA TRAFFIC se benefician igualmente de las oportunidades adicionales del grupo Schneider, orientado internacionalmente. Adem\u00e1s, el grupo Schneider complementa su oferta de servicios con esta fusi\u00f3n y los servicios especializados de NOVA TRAFFIC.<\/p>\n<p>El grupo Schneider adquiere el 100 % de las acciones de NOVA TRAFFIC del director general y propietario Daniel Stein. A cambio, Daniel Stein participar\u00e1 en el grupo Schneider y se unir\u00e1 a la direcci\u00f3n del grupo Schneider. Adem\u00e1s, continuar\u00e1 dirigiendo NOVA TRAFFIC como hasta ahora.<\/p>\n<p>Andr\u00e9 Strebel, CEO, coment\u00f3: <em>\u00abEstoy emocionado por la colaboraci\u00f3n con Nova Traffic y Daniel Stein. La empresa es el complemento perfecto para el grupo Schneider. Estoy seguro de que nos beneficiaremos mutuamente y emprenderemos un camino exitoso juntos.\u00bb<\/em><\/p>\n<p>Daniel Stein a\u00f1ade: <em>\u00abHablamos el mismo idioma y compartimos los mismos valores. Nos preocupamos por nuestros empleados. Nuestros clientes y socios en todo el mundo tambi\u00e9n. Todos se beneficiar\u00e1n de este camino conjunto. Personalmente, estoy contento de haber podido encontrar una planificaci\u00f3n futura sostenible para mis empleados y mi empresa con el grupo Schneider. Tambi\u00e9n espero con ansias las nuevas tareas y la colaboraci\u00f3n en la direcci\u00f3n del grupo Schneider.\u00bb<\/em><\/p>\n<p>Foto: Pixabay \/ Wolfgang Schr\u00f6pfer<\/p>\n<p><strong>Sobre el grupo Schneider<\/strong><\/p>\n<p>Fundado en 1865, el grupo Schneider es una empresa de transporte de tama\u00f1o medio orientada internacionalmente. En m\u00e1s de 25 ubicaciones en Suiza, Europa, EE. UU. y Asia, y con la ayuda de una red de socios mundial, el especialista en log\u00edstica planifica y coordina el transporte de mercanc\u00edas en el tr\u00e1fico transfronterizo para sus clientes. Adem\u00e1s de transportes por carretera, transporte mar\u00edtimo y a\u00e9reo, Schneider ofrece servicios amplios, especialmente en el \u00e1rea de aduanas, servicios log\u00edsticos de valor a\u00f1adido y servicios especiales.<\/p>\n<p><a href=\"https:\/\/www.schneider-transport.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.schneider-transport.com<\/a><\/p>\n<p><strong>Sobre NOVA Traffic<\/strong><\/p>\n<p>NOVA TRAFFIC fue fundada en 1982 en Z\u00farich. Al principio, el enfoque estaba en el transporte a\u00e9reo. Paso a paso, se ampli\u00f3 la cartera. Hoy en d\u00eda, NOVA TRAFFIC ofrece toda la gama de productos de un transportista global. Adem\u00e1s de transportes a\u00e9reos, tambi\u00e9n transportes terrestres en toda Europa, transporte mar\u00edtimo internacional, conceptos de externalizaci\u00f3n individuales y soluciones inteligentes de log\u00edstica de almacenamiento y log\u00edstica de comercio electr\u00f3nico. La empresa se apoya en una red mundial de socios probados y fiables. Desde 2007, Daniel Stein es el director general y propietario de NOVA TRAFFIC.<\/p>\n<p><a href=\"https:\/\/www.novatraffic.ch\" target=\"_blank\" rel=\"noopener noreferrer\">www.novatraffic.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proveedor de servicios log\u00edsticos Schneider &amp; Cie. AG con sede en Basilea adquiere el 100 % de las acciones de Nova Traffic AG con sede<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1557,1556,1560,1561,1559],"tags":[],"class_list":["post-17709","post","type-post","status-publish","format-standard","hentry","category-air-freight","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"El proveedor de servicios log\u00edsticos Schneider &amp; Cie. AG con sede en Basilea adquiere el 100 % de las acciones de Nova Traffic AG con sede [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-29T08:32:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:28:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Schneider y Nova Traffic van juntos hacia el futuro\",\"datePublished\":\"2020-05-29T08:32:51+00:00\",\"dateModified\":\"2025-12-15T11:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"articleSection\":[\"Air Freight\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/\",\"name\":\"Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\"},\"datePublished\":\"2020-05-29T08:32:51+00:00\",\"dateModified\":\"2025-12-15T11:28:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/2020\\\/05\\\/29\\\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schneider y Nova Traffic van juntos hacia el futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#organization\",\"name\":\"Grupo Logismedia AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Grupo Logismedia AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/","og_locale":"es_ES","og_type":"article","og_title":"Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24","og_description":"El proveedor de servicios log\u00edsticos Schneider &amp; Cie. AG con sede en Basilea adquiere el 100 % de las acciones de Nova Traffic AG con sede [\u2026]","og_url":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-05-29T08:32:51+00:00","article_modified_time":"2025-12-15T11:28:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/"},"author":{"name":"","@id":""},"headline":"Schneider y Nova Traffic van juntos hacia el futuro","datePublished":"2020-05-29T08:32:51+00:00","dateModified":"2025-12-15T11:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"articleSection":["Air Freight","Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions","Shipping &amp; Ports"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/","url":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/","name":"Schneider y Nova Traffic van juntos hacia el futuro - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/es\/#website"},"datePublished":"2020-05-29T08:32:51+00:00","dateModified":"2025-12-15T11:28:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/es\/2020\/05\/29\/schneider-y-nova-traffic-van-juntos-hacia-el-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/es\/"},{"@type":"ListItem","position":2,"name":"Schneider y Nova Traffic van juntos hacia el futuro"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/es\/#website","url":"https:\/\/loginfo24.com\/es\/","name":"Loginfo24","description":"Loginfo24 es la plataforma dedicada a la log\u00edstica y las cadenas de suministro con informaci\u00f3n las 24 horas del d\u00eda.","publisher":{"@id":"https:\/\/loginfo24.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/es\/#organization","name":"Grupo Logismedia AG","url":"https:\/\/loginfo24.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Grupo Logismedia AG"},"image":{"@id":"https:\/\/loginfo24.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/17709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/comments?post=17709"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/17709\/revisions"}],"predecessor-version":[{"id":31760,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/posts\/17709\/revisions\/31760"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/media?parent=17709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/categories?post=17709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/es\/wp-json\/wp\/v2\/tags?post=17709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}