{"id":84313,"date":"2026-07-15T08:10:03","date_gmt":"2026-07-15T08:10:03","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/"},"modified":"2026-07-15T08:10:03","modified_gmt":"2026-07-15T08:10:03","slug":"carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/","title":{"rendered":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility"},"content":{"rendered":"<p>DKV Mobility has appointed Carlos Soares to the newly created position of Chief Data &amp; AI Officer to consolidate responsibility for data, analytics, and the use of artificial intelligence within the company. He will report directly to Jesper Erichsen, Chief Technology &amp; Operating Officer, and is expected to further develop DKV Mobility&#8217;s data-driven offerings to provide additional value to customers.<\/p>\n<p>Erichsen emphasizes the importance of data and artificial intelligence in developing efficient solutions. He states, &#8222;With the newly created position of Chief Data &amp; AI Officer, we ensure that we consistently advance these topics across all business areas.&#8220; Soares brings the necessary strategic experience and operational implementation strength to achieve these goals.<\/p>\n<p>Soares himself comments on his new role, highlighting that DKV Mobility possesses one of the largest data foundations in the European mobility market. He sees great potential in utilizing this data and strategically employing artificial intelligence to provide customers with tangible added value.<\/p>\n<p>Soares has extensive experience in building data and AI organizations in international companies. Prior to his appointment, he served as Data &amp; AI Officer at Brenntag SE from 2021 until early 2026, where he established the company&#8217;s global data, analytics, and AI function. Additionally, he was active as the founder and managing director of the consulting firm Northaxis Partners, advising companies on the development and implementation of their data and AI strategies.<\/p>\n<p>DKV Mobility is a platform for international mobility services with approximately 441,000 active customers in over 50 countries and around 2,800 employees. The company provides access to an extensive network of fuel stations and charging points, as well as toll solutions and vehicle services. In 2025, DKV Mobility achieved a transaction volume of EUR 20 billion and a revenue of EUR 860 million.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.dkv-mobility.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.dkv-mobility.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DKV Mobility has appointed Carlos Soares as Chief Data &#038; AI Officer to optimize the data strategy and the use of Artificial Intelligence within the company.<\/p>\n","protected":false},"author":12,"featured_media":84314,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6679,6675,1556,1555],"tags":[8270,36503,36504,5396,36505,8004,36506,36507,36508,36509,36510,8278,36511,36512,36513,33408,2211,2212,36514,36515,36516,2700,36517,2123,36518,8024,5408,2279,2280,3561,2065,2282,36519,36520,36521,7689,36522,1869,36523,10201,36524,36525,2731,36526,36527,36528,2106,7699,36529,36530,36531,36532,36533,2242],"class_list":["post-84313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-germany","category-intermodal-road","category-people-companies","tag-analyse-de-donnees","tag-analytics-solutions","tag-analytics-loesungen","tag-artificial-intelligence","tag-carlos-soares","tag-charging-infrastructure","tag-chief-data-officer","tag-data-analytics","tag-data-management","tag-data-strategy","tag-data-driven-offerings-francais-dkv-mobility","tag-datenanalyse","tag-datengetriebenes-angebot-english-dkv-mobility","tag-datenmanagement","tag-datenstrategie","tag-deutsch-dkv-mobility","tag-digital-transformation","tag-digitale-transformation","tag-directeur-des-donnees","tag-europaeischer-mobilitaetsmarkt","tag-european-mobility-market","tag-fachkraeftemangel-in-der-logistik","tag-fuel-station-network","tag-gestion-de-la-chaine-dapprovisionnement","tag-gestion-des-donnees","tag-infrastructure-de-recharge","tag-intelligence-artificielle","tag-international-logistics","tag-internationale-logistik","tag-kuenstliche-intelligenz","tag-ladeinfrastruktur","tag-logistique-internationale","tag-marche-de-la-mobilite-europeenne","tag-mautloesungen","tag-mobilitaetsdienstleistungen","tag-mobilite-durable","tag-mobility-services","tag-nachhaltige-mobilitaet","tag-offres-basees-sur-les-donnees","tag-penurie-de-competences-en-logistique","tag-reseau-de-stations-service","tag-services-de-mobilite","tag-skills-shortage-in-logistics","tag-solutions-danalyse","tag-solutions-de-peage","tag-strategie-de-donnees","tag-supply-chain-management","tag-sustainable-mobility","tag-tankstellennetzwerk","tag-technologie-dans-la-mobilite","tag-technologie-in-der-mobilitaet","tag-technology-in-mobility","tag-toll-solutions","tag-transformation-numerique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"DKV Mobility has appointed Carlos Soares as Chief Data &amp; AI Officer to optimize the data strategy and the use of Artificial Intelligence within the company.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T08:10:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility\",\"datePublished\":\"2026-07-15T08:10:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/\"},\"wordCount\":299,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/07\\\/Photo_Carlos-Soares.png\",\"keywords\":[\"analyse de donn\u00e9es\",\"analytics solutions\",\"Analytics-L\u00f6sungen\",\"artificial intelligence\",\"Carlos Soares\",\"charging infrastructure\",\"Chief Data Officer\",\"data analytics\",\"data management\",\"data strategy\",\"data-driven offerings Fran\u00e7ais DKV Mobility\",\"Datenanalyse\",\"Datengetriebenes Angebot English DKV Mobility\",\"Datenmanagement\",\"Datenstrategie\",\"Deutsch DKV Mobility\",\"digital transformation\",\"digitale Transformation\",\"directeur des donn\u00e9es\",\"europ\u00e4ischer Mobilit\u00e4tsmarkt\",\"European mobility market\",\"Fachkr\u00e4ftemangel in der Logistik\",\"fuel station network\",\"gestion de la cha\u00eene d'approvisionnement\",\"gestion des donn\u00e9es\",\"infrastructure de recharge\",\"intelligence artificielle\",\"international logistics\",\"internationale Logistik\",\"K\u00fcnstliche Intelligenz\",\"Ladeinfrastruktur\",\"logistique internationale\",\"march\u00e9 de la mobilit\u00e9 europ\u00e9enne\",\"Mautl\u00f6sungen\",\"Mobilit\u00e4tsdienstleistungen\",\"mobilit\u00e9 durable\",\"mobility services\",\"nachhaltige Mobilit\u00e4t\",\"offres bas\u00e9es sur les donn\u00e9es\",\"p\u00e9nurie de comp\u00e9tences en logistique\",\"r\u00e9seau de stations-service\",\"services de mobilit\u00e9\",\"skills shortage in logistics\",\"solutions d'analyse\",\"solutions de p\u00e9age\",\"strat\u00e9gie de donn\u00e9es\",\"Supply Chain Management\",\"sustainable mobility\",\"Tankstellennetzwerk\",\"technologie dans la mobilit\u00e9\",\"Technologie in der Mobilit\u00e4t\",\"technology in mobility\",\"toll solutions\",\"transformation num\u00e9rique\"],\"articleSection\":[\"Europa\",\"Germany\",\"Intermodal \\\/ Road\",\"People &amp; Companies\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/\",\"name\":\"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/07\\\/Photo_Carlos-Soares.png\",\"datePublished\":\"2026-07-15T08:10:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/07\\\/Photo_Carlos-Soares.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/07\\\/Photo_Carlos-Soares.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/2026\\\/07\\\/15\\\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 is the platform for logistics and supply chains, providing information around the clock.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/en\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/","og_locale":"en_US","og_type":"article","og_title":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24","og_description":"DKV Mobility has appointed Carlos Soares as Chief Data & AI Officer to optimize the data strategy and the use of Artificial Intelligence within the company.","og_url":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-07-15T08:10:03+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png","type":"image\/png"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andreas Haug","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/loginfo24.com\/en\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility","datePublished":"2026-07-15T08:10:03+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/"},"wordCount":299,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/en\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png","keywords":["analyse de donn\u00e9es","analytics solutions","Analytics-L\u00f6sungen","artificial intelligence","Carlos Soares","charging infrastructure","Chief Data Officer","data analytics","data management","data strategy","data-driven offerings Fran\u00e7ais DKV Mobility","Datenanalyse","Datengetriebenes Angebot English DKV Mobility","Datenmanagement","Datenstrategie","Deutsch DKV Mobility","digital transformation","digitale Transformation","directeur des donn\u00e9es","europ\u00e4ischer Mobilit\u00e4tsmarkt","European mobility market","Fachkr\u00e4ftemangel in der Logistik","fuel station network","gestion de la cha\u00eene d'approvisionnement","gestion des donn\u00e9es","infrastructure de recharge","intelligence artificielle","international logistics","internationale Logistik","K\u00fcnstliche Intelligenz","Ladeinfrastruktur","logistique internationale","march\u00e9 de la mobilit\u00e9 europ\u00e9enne","Mautl\u00f6sungen","Mobilit\u00e4tsdienstleistungen","mobilit\u00e9 durable","mobility services","nachhaltige Mobilit\u00e4t","offres bas\u00e9es sur les donn\u00e9es","p\u00e9nurie de comp\u00e9tences en logistique","r\u00e9seau de stations-service","services de mobilit\u00e9","skills shortage in logistics","solutions d'analyse","solutions de p\u00e9age","strat\u00e9gie de donn\u00e9es","Supply Chain Management","sustainable mobility","Tankstellennetzwerk","technologie dans la mobilit\u00e9","Technologie in der Mobilit\u00e4t","technology in mobility","toll solutions","transformation num\u00e9rique"],"articleSection":["Europa","Germany","Intermodal \/ Road","People &amp; Companies"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/","url":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/","name":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png","datePublished":"2026-07-15T08:10:03+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/07\/Photo_Carlos-Soares.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/en\/2026\/07\/15\/carlos-soares-appointed-chief-data-ai-officer-at-dkv-mobility\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/en\/"},{"@type":"ListItem","position":2,"name":"Carlos Soares appointed Chief Data &#038; AI Officer at DKV Mobility"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/en\/#website","url":"https:\/\/loginfo24.com\/en\/","name":"Loginfo24","description":"Loginfo24 is the platform for logistics and supply chains, providing information around the clock.","publisher":{"@id":"https:\/\/loginfo24.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/en\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/loginfo24.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/en\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/loginfo24.com\/en\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/posts\/84313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/comments?post=84313"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/posts\/84313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/media\/84314"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/media?parent=84313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/categories?post=84313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/en\/wp-json\/wp\/v2\/tags?post=84313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}